{"id":145026,"date":"2026-06-24T11:19:29","date_gmt":"2026-06-24T15:19:29","guid":{"rendered":"https:\/\/www.n2growth.com\/?post_type=interviews&#038;p=145026"},"modified":"2026-07-15T10:10:16","modified_gmt":"2026-07-15T14:10:16","slug":"joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today","status":"publish","type":"interviews","link":"https:\/\/www.n2growth.com\/es_mx\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/","title":{"rendered":"Joshua Foltz, ex CISO de NerdWallet, habla sobre lo que se necesita para liderar la seguridad hoy en d\u00eda."},"content":{"rendered":"<section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><img decoding=\"async\" class=\"alignleft wp-image-145027\" src=\"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz-300x278.jpg\" alt=\"Una conversaci\u00f3n con Joshua Foltz, ex CISO de NerdWallet.\" width=\"230\" height=\"213\" srcset=\"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz-300x278.jpg 300w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz-1024x947.jpg 1024w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz-13x12.jpg 13w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz-150x139.jpg 150w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz.jpg 1084w\" sizes=\"(max-width: 230px) 100vw, 230px\" \/><\/p>\n<p>El rol del CISO est\u00e1 cambiando r\u00e1pidamente, y los consejos de administraci\u00f3n se preguntan con raz\u00f3n c\u00f3mo deber\u00eda afectar esto a qui\u00e9n contratan. En esta conversaci\u00f3n, <a href=\"https:\/\/www.linkedin.com\/in\/joshuafoltz\/\">Joshua Foltz<\/a> Argumenta que un liderazgo eficaz en materia de seguridad requiere tanta visi\u00f3n empresarial como profundidad t\u00e9cnica, explica por qu\u00e9 la IA es el arma m\u00e1s poderosa que jam\u00e1s haya tenido la industria de la seguridad y sostiene que la creatividad y la adaptabilidad son las cualidades que los consejos de administraci\u00f3n deben priorizar al buscar un CISO que pueda liderarlos en un entorno tecnol\u00f3gico en constante cambio.<\/p>\n<p>Joshua Foltz es un ejecutivo de ciberseguridad e IA con m\u00e1s de veinte a\u00f1os de experiencia en entornos de tecnolog\u00eda financiera, tecnolog\u00eda de seguros, SaaS y tecnolog\u00eda regulada, incluyendo su rol m\u00e1s reciente como CISO en <a href=\"https:\/\/www.nerdwallet.com\/\">NerdWallet<\/a>. Posee un MBA de Yale y ha desarrollado su carrera profesional en la intersecci\u00f3n de la seguridad, la gobernanza de la IA y la transformaci\u00f3n empresarial.<\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2><span class=\"ez-toc-section\" id=\"How_do_you_think_about_where_the_CISO_role_is_heading\"><\/span>\u00bfQu\u00e9 opinas sobre hacia d\u00f3nde se dirige el rol del CISO?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Para las empresas que est\u00e1n adoptando la IA, el rol est\u00e1 cambiando dr\u00e1sticamente. La mayor\u00eda de mis colegas que han sido CISO durante a\u00f1os se muestran reacios a usarla, y creo que esa reticencia es un verdadero obst\u00e1culo. La IA es la mejor arma que hemos visto en ciberseguridad. Estamos trabajando para poder entregar c\u00f3digo libre de vulnerabilidades antes de que llegue a producci\u00f3n. No podr\u00eda haber dicho eso hace unos a\u00f1os. La tecnolog\u00eda simplemente no estaba lo suficientemente desarrollada.<\/p>\n<p>Esto significa que los CISO que adopten la IA deber\u00e1n ser, en parte, l\u00edderes de seguridad y, en parte, ingenieros. Mitad ingeniero de IA, mitad desarrollador. Es fundamental comprender qu\u00e9 producen las herramientas y de qu\u00e9 son capaces, ya que, en esencia, se dedican a crear aplicaciones constantemente. Liderar un equipo de ingenieros de seguridad que tambi\u00e9n sean desarrolladores es el futuro de este sector, y creo que lo estamos logrando m\u00e1s r\u00e1pido de lo que muchos esperan.<\/p>\n<p>Las fronteras entre CISO y Director de IA se est\u00e1n difuminando. Un CISO que realmente adopta la IA y un responsable de IA que se toma en serio la seguridad son, en este punto, pr\u00e1cticamente el mismo rol.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"You_came_to_the_CISO_role_with_an_MBA_and_a_background_in_product_and_software_development_alongside_your_security_credentials_That_is_not_the_typical_profile_How_has_that_broader_background_shaped_your_work_and_do_you_think_the_role_demands_more_business_fluency_than_most_organizations_assume_when_they_are_hiring\"><\/span>Llegaste al puesto de CISO con un MBA y experiencia en desarrollo de productos y software, adem\u00e1s de tus credenciales en seguridad. Ese no es el perfil t\u00edpico. \u00bfC\u00f3mo ha influido esa experiencia m\u00e1s amplia en tu trabajo? \u00bfCrees que el puesto exige una mayor comprensi\u00f3n del mundo empresarial de la que suelen asumir las organizaciones al contratar personal?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La comprensi\u00f3n del entorno empresarial es fundamental para ser un CISO eficaz. Muchos de los l\u00edderes de seguridad m\u00e1s capacitados t\u00e9cnicamente tienen dificultades precisamente porque desenvolverse en un consejo de administraci\u00f3n y en un equipo ejecutivo es esencial para lograr resultados. Existe una cultura de seguridad que se basa en el miedo, la incertidumbre y la duda para tomar decisiones. Si bien este enfoque tiene su utilidad, no es suficiente. Comprender las necesidades y deseos de la empresa, y luego implementar medidas de seguridad en funci\u00f3n de ellos, representa una enorme ventaja.<\/p>\n<p>Al mismo tiempo, no se puede obviar la profundidad t\u00e9cnica. Ignorarla te convierte en un CISO bastante ineficaz, porque no comprendes realmente los riesgos que gestionas. Ser CISO es como jugar con fuego todo el d\u00eda. Si sabes lo que haces, comprendes las repercusiones, sabes qu\u00e9 puede salir mal y sabes qu\u00e9 hacer cuando sucede, no podr\u00e1s evitarlo. He visto c\u00f3mo a otras personas les ha salido mal. Necesitas ambas cosas para tener \u00e9xito.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Most_of_the_security_conversation_right_now_is_dominated_by_AI_What_I_want_to_know_is_what_forward-thinking_CISOs_should_be_doing_today_to_prepare_for_the_risk_that_quantum_computing_may_soon_pose\"><\/span>Actualmente, la mayor parte del debate sobre seguridad gira en torno a la IA. Lo que me interesa saber es qu\u00e9 deber\u00edan hacer hoy los CISO con visi\u00f3n de futuro para prepararse ante el riesgo que la computaci\u00f3n cu\u00e1ntica podr\u00eda suponer pr\u00f3ximamente.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La computaci\u00f3n cu\u00e1ntica es compleja, y la raz\u00f3n es estructural. Los CISO, por naturaleza, se centran en los problemas urgentes. Alguien me describi\u00f3 una vez su funci\u00f3n como la de ser arrojado al medio de un incendio forestal con la tarea de encontrar el l\u00edmite. Si algo no es urgente y cr\u00edtico, la mayor\u00eda no le prestamos mucha atenci\u00f3n, a menos que seamos deliberadamente estrat\u00e9gicos.<\/p>\n<p>La computaci\u00f3n cu\u00e1ntica se incluye en esta categor\u00eda actualmente. Sabemos que, con el tiempo, lograr\u00e1 romper la mayor\u00eda de los sistemas de cifrado. Los est\u00e1ndares de cifrado preparados para la computaci\u00f3n cu\u00e1ntica que se est\u00e1n desarrollando son te\u00f3ricamente s\u00f3lidos, pero a\u00fan no sabemos con certeza c\u00f3mo se comportar\u00e1n. Actualizar la criptograf\u00eda, migrar a claves de acceso, reforzar la autenticaci\u00f3n de dos factores: todo esto ser\u00e1 necesario, y es un trabajo factible. Los expertos ya est\u00e1n trabajando en los est\u00e1ndares, y el resto los adoptaremos.<\/p>\n<p>Mi opini\u00f3n sincera es que las criptomonedas ser\u00e1n el primer objetivo cuando la computaci\u00f3n cu\u00e1ntica sea capaz de lograrlo. El primer pa\u00eds en conseguirlo probablemente ir\u00e1 tras Bitcoin, y el revuelo que esto genere dar\u00e1 tiempo a los dem\u00e1s para poner en orden su sistema de cifrado.<\/p>\n<p>Lo que deber\u00edan hacer los consejos de administraci\u00f3n es preguntar a sus CISO qu\u00e9 planes tienen al respecto. Los CISO deben estar al tanto de la situaci\u00f3n. Por lo que entiendo, existen aproximadamente ocho problemas fundamentales que la computaci\u00f3n cu\u00e1ntica debe resolver, y cerca de la mitad ya se han resuelto. Tenemos tiempo. Y navegar por el actual panorama de la IA tiene una ventaja: la velocidad y la adaptabilidad que impone a los equipos de seguridad son precisamente la preparaci\u00f3n necesaria. Un CISO que sobreviva a este periodo estar\u00e1 bien posicionado cuando llegue la computaci\u00f3n cu\u00e1ntica.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"The_boundary_between_security_and_product_engineering_seems_to_be_shifting_How_do_you_think_about_where_securitys_responsibility_ends_and_engineerings_begins\"><\/span>La frontera entre seguridad e ingenier\u00eda de producto parece estar desdibuj\u00e1ndose. \u00bfC\u00f3mo defines d\u00f3nde termina la responsabilidad de seguridad y comienza la de ingenier\u00eda?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Son dos caras de la misma moneda, y eso no cambiar\u00e1. La ingenier\u00eda de producto se centra en lograr que las cosas funcionen bien y en mejorar la experiencia. La seguridad se centra en explorar los l\u00edmites de la construcci\u00f3n y encontrar las vulnerabilidades que los ingenieros funcionales no detectan. Ambas perspectivas son necesarias, y ninguna es mejor que la otra. Simplemente son diferentes.<\/p>\n<p>Al inicio de la carrera de un CISO, esa tensi\u00f3n puede ser dif\u00edcil de manejar. Que los equipos de seguridad se presenten para decirles a los ingenieros que han cometido un error no es una conversaci\u00f3n agradable, y el conflicto subyacente suele girar en torno al tiempo y los recursos. Aprender a replantear esa relaci\u00f3n, a presentarse como un socio en lugar de una funci\u00f3n de auditor\u00eda, es una de las cosas m\u00e1s dif\u00edciles que un CISO debe comprender. Me llev\u00f3 a\u00f1os lograrlo.<\/p>\n<p>M\u00e1s all\u00e1 de la experiencia, lo que ha acelerado este cambio es la IA. Tareas que antes consum\u00edan semanas de trabajo de ingenier\u00eda ahora se pueden realizar en minutos. Cuando la seguridad deja de ser un obst\u00e1culo, la comunicaci\u00f3n con los equipos de producto cambia por completo y las barreras que antes defin\u00edan esa relaci\u00f3n comienzan a desaparecer por s\u00ed solas.<\/p>\n<p>La confianza es clave para lograrlo. Entender qu\u00e9 motiva a los equipos de producto, a qu\u00e9 se resisten y convertirse en su aliado en lugar de un adversario es la forma de generar confianza y, a trav\u00e9s de ella, conseguir resultados. Sencillo en teor\u00eda, pero dif\u00edcil en la pr\u00e1ctica.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"If_you_were_sitting_in_a_room_full_of_CEOs_and_board_members_about_to_conduct_a_CISO_search_what_should_be_on_their_radar_that_might_not_be\"><\/span>Si estuvieras en una sala llena de directores ejecutivos y miembros de la junta directiva a punto de realizar una b\u00fasqueda de CISO, \u00bfqu\u00e9 deber\u00eda estar en su radar que quiz\u00e1s no lo est\u00e9?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Creatividad y capacidad de adaptaci\u00f3n. Esas son las cualidades que con mayor frecuencia se pasan por alto.<\/p>\n<p>Los riesgos que los CISO deber\u00e1n gestionar a finales de este a\u00f1o son riesgos que apenas hemos empezado a considerar. Hace un a\u00f1o, la IA con agentes y su potencial dentro de un entorno empresarial, conectada a todo mediante un servidor como MCP, no era un riesgo que la mayor\u00eda de los equipos de seguridad tuvieran en cuenta. Hace seis meses, apenas figuraba en el radar de nadie. El ritmo al que surgen nuevas amenazas es extraordinario, y el CISO del futuro debe ser capaz de aprender r\u00e1pidamente una nueva tecnolog\u00eda, probarla, determinar c\u00f3mo protegerla e implementar esa seguridad de forma que no frene la innovaci\u00f3n que la empresa busca impulsar.<\/p>\n<p>Eso requiere verdadera creatividad. Lo interesante es que la trayectoria tradicional en seguridad \u2014hacking, pruebas de penetraci\u00f3n, ejercicios de simulaci\u00f3n de ataques\u2014 fomenta precisamente ese tipo de pensamiento. Se analiza un problema y se encuentran soluciones inesperadas. Ese instinto es directamente transferible. Los CISO que se forman en esos \u00e1mbitos siguen siendo una fuente importante de talento.<\/p>\n<p>Pero los consejos de administraci\u00f3n deben buscar expl\u00edcitamente esas cualidades creativas y de adaptaci\u00f3n, no solo verificar las credenciales t\u00e9cnicas o los a\u00f1os de experiencia. La perspicacia t\u00e9cnica es importante, pero es un requisito b\u00e1sico. Lo que diferenciar\u00e1 a los CISO que prosperan de los que no lo hacen es la capacidad de desenvolverse en condiciones que no exist\u00edan cuando comenzaron en el puesto.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>Una conversaci\u00f3n con Joshua Foltz, ex CISO de NerdWallet.<\/p>","protected":false},"author":1,"featured_media":145027,"template":"","interview-categories":[11362],"class_list":["post-145026","interviews","type-interviews","status-publish","has-post-thumbnail","hentry","interview-categories-cybersecurity"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Joshua Foltz, Former NerdWallet CISO, on security leadership<\/title>\n<meta name=\"description\" content=\"Former NerdWallet CISO Joshua Foltz on why creativity matters more than credentials in CISO hiring, how AI is transforming security, and what boards miss.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.n2growth.com\/es_mx\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joshua Foltz, Former NerdWallet CISO, on security leadership\" \/>\n<meta property=\"og:description\" content=\"Former NerdWallet CISO Joshua Foltz on why creativity matters more than credentials in CISO hiring, how AI is transforming security, and what boards miss.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.n2growth.com\/es_mx\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/\" \/>\n<meta property=\"og:site_name\" content=\"N2Growth\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/n2growth\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T14:10:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1084\" \/>\n\t<meta property=\"og:image:height\" content=\"1003\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Joshua Foltz, Former NerdWallet CISO, on security leadership\" \/>\n<meta name=\"twitter:description\" content=\"Former NerdWallet CISO Joshua Foltz on why creativity matters more than credentials in CISO hiring, how AI is transforming security, and what boards miss.\" \/>\n<meta name=\"twitter:site\" content=\"@n2growth\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Joshua Foltz, ex CISO de NerdWallet, habla sobre liderazgo en seguridad.","description":"Joshua Foltz, ex CISO de NerdWallet, explica por qu\u00e9 la creatividad importa m\u00e1s que las credenciales a la hora de contratar a un CISO, c\u00f3mo la IA est\u00e1 transformando la seguridad y qu\u00e9 pasan por alto los consejos de administraci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.n2growth.com\/es_mx\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/","og_locale":"es_MX","og_type":"article","og_title":"Joshua Foltz, Former NerdWallet CISO, on security leadership","og_description":"Former NerdWallet CISO Joshua Foltz on why creativity matters more than credentials in CISO hiring, how AI is transforming security, and what boards miss.","og_url":"https:\/\/www.n2growth.com\/es_mx\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/","og_site_name":"N2Growth","article_publisher":"https:\/\/www.facebook.com\/n2growth","article_modified_time":"2026-07-15T14:10:16+00:00","og_image":[{"width":1084,"height":1003,"url":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Joshua Foltz, Former NerdWallet CISO, on security leadership","twitter_description":"Former NerdWallet CISO Joshua Foltz on why creativity matters more than credentials in CISO hiring, how AI is transforming security, and what boards miss.","twitter_site":"@n2growth","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.n2growth.com\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/","url":"https:\/\/www.n2growth.com\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/","name":"Joshua Foltz, ex CISO de NerdWallet, habla sobre liderazgo en seguridad.","isPartOf":{"@id":"https:\/\/www.n2growth.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.n2growth.com\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/#primaryimage"},"image":{"@id":"https:\/\/www.n2growth.com\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/#primaryimage"},"thumbnailUrl":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz.jpg","datePublished":"2026-06-24T15:19:29+00:00","dateModified":"2026-07-15T14:10:16+00:00","description":"Joshua Foltz, ex CISO de NerdWallet, explica por qu\u00e9 la creatividad importa m\u00e1s que las credenciales a la hora de contratar a un CISO, c\u00f3mo la IA est\u00e1 transformando la seguridad y qu\u00e9 pasan por alto los consejos de administraci\u00f3n.","breadcrumb":{"@id":"https:\/\/www.n2growth.com\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.n2growth.com\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.n2growth.com\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/#primaryimage","url":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz.jpg","contentUrl":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz.jpg","width":1084,"height":1003,"caption":"A conversation with Joshua Foltz, former CISO at NerdWallet"},{"@type":"BreadcrumbList","@id":"https:\/\/www.n2growth.com\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.n2growth.com\/"},{"@type":"ListItem","position":2,"name":"Joshua Foltz, former CISO at NerdWallet, on what it takes to lead security today"}]},{"@type":"WebSite","@id":"https:\/\/www.n2growth.com\/#website","url":"https:\/\/www.n2growth.com\/","name":"N2Growth","description":"Encontramos y desarrollamos los mejores l\u00edderes del mundo&#039;","publisher":{"@id":"https:\/\/www.n2growth.com\/#organization"},"alternateName":"N2 Growth","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.n2growth.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.n2growth.com\/#organization","name":"N2Growth","alternateName":"N2 Growth","url":"https:\/\/www.n2growth.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.n2growth.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2019\/05\/N2Growth-Logo-Dark.png","contentUrl":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2019\/05\/N2Growth-Logo-Dark.png","width":500,"height":142,"caption":"N2Growth"},"image":{"@id":"https:\/\/www.n2growth.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/n2growth","https:\/\/x.com\/n2growth","https:\/\/www.instagram.com\/n2growth","https:\/\/www.linkedin.com\/company\/n2growth","https:\/\/www.pinterest.com\/gon2growth\/","https:\/\/www.youtube.com\/c\/n2growth-"],"description":"Firma global de b\u00fasqueda de ejecutivos, coaching ejecutivo y asesor\u00eda de liderazgo","email":"press@n2growth.com","telephone":"+18009444662","legalName":"N2Growth Inc.","foundingDate":"2006-05-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}}]}},"_links":{"self":[{"href":"https:\/\/www.n2growth.com\/es_mx\/wp-json\/wp\/v2\/interviews\/145026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.n2growth.com\/es_mx\/wp-json\/wp\/v2\/interviews"}],"about":[{"href":"https:\/\/www.n2growth.com\/es_mx\/wp-json\/wp\/v2\/types\/interviews"}],"author":[{"embeddable":true,"href":"https:\/\/www.n2growth.com\/es_mx\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.n2growth.com\/es_mx\/wp-json\/wp\/v2\/media\/145027"}],"wp:attachment":[{"href":"https:\/\/www.n2growth.com\/es_mx\/wp-json\/wp\/v2\/media?parent=145026"}],"wp:term":[{"taxonomy":"interview-categories","embeddable":true,"href":"https:\/\/www.n2growth.com\/es_mx\/wp-json\/wp\/v2\/interview-categories?post=145026"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}