{"id":146772,"date":"2026-08-20T05:09:32","date_gmt":"2026-08-20T09:09:32","guid":{"rendered":"https:\/\/www.n2growth.com\/?post_type=interviews&#038;p=146772"},"modified":"2026-08-19T23:48:05","modified_gmt":"2026-08-20T03:48:05","slug":"madhuri-andrews-on-people-first-technology-leadership","status":"publish","type":"interviews","link":"https:\/\/www.n2growth.com\/es_mx\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/","title":{"rendered":"Madhuri Andrews habla sobre el liderazgo tecnol\u00f3gico centrado en las personas."},"content":{"rendered":"<section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><img decoding=\"async\" class=\"alignleft wp-image-146771 size-medium\" src=\"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews-300x278.jpg\" alt=\"Conversaci\u00f3n con Madhuri Andrews, vicepresidenta ejecutiva y directora de inform\u00e1tica de MKS Inc., y miembro del consejo de administraci\u00f3n de Applied Industrial Technologies, Inc.\" width=\"300\" height=\"278\" srcset=\"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews-300x278.jpg 300w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews-1024x947.jpg 1024w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews-13x12.jpg 13w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews-150x139.jpg 150w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews.jpg 1084w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">En un momento en que la tecnolog\u00eda cambia m\u00e1s r\u00e1pido de lo que la mayor\u00eda de las organizaciones pueden asimilar, el liderazgo tecnol\u00f3gico es m\u00e1s importante que nunca. Madhuri nos recuerda que el liderazgo centrado en las personas sigue siendo fundamental para la eficacia de los CIO, explica c\u00f3mo se traduce esto de la filosof\u00eda a la pr\u00e1ctica, comparte su visi\u00f3n sobre lo que los consejos de administraci\u00f3n deber\u00edan buscar en un CIO y, bas\u00e1ndose en su experiencia como CIO y miembro del consejo, expone los requisitos para que un CIO alcance el \u00e9xito.<\/span><\/p>\n<p><a href=\"https:\/\/www.linkedin.com\/in\/madhuri-andrews\/\"><span style=\"font-weight: 400;\">Madhuri Andrews<\/span><\/a><span style=\"font-weight: 400;\"> es vicepresidente ejecutivo y director de inform\u00e1tica en <\/span><a href=\"https:\/\/www.mks.com\/\"><span style=\"font-weight: 400;\">MKS<\/span><\/a><span style=\"font-weight: 400;\">, donde lidera la estrategia tecnol\u00f3gica de la empresa, impulsando el crecimiento y la excelencia operativa en una organizaci\u00f3n global. Ejecutiva de tecnolog\u00eda y negocios con experiencia en los sectores aeroespacial y de defensa, industrial, de alta tecnolog\u00eda, infraestructura y servicios profesionales, tambi\u00e9n es miembro del consejo de administraci\u00f3n de Applied Industrial Technologies, Inc. (AIT). Ha sido reconocida como una de las 100 mejores CIO del mundo, incluida en el Sal\u00f3n de la Fama de los CIO, galardonada con el premio BostonCIO ORBIE Global Award y nombrada entre los 100 mejores profesionales asi\u00e1tico-americanos del sector, entre otros reconocimientos.<\/span><\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2><span class=\"ez-toc-section\" id=\"To_start_we_all_know_technology_is_changing_at_a_remarkable_pace_right_now_but_I_want_to_be_a_bit_counterintuitive_and_ask_about_the_other_side_of_that_story_What_do_you_think_are_the_keys_to_success_as_a_CIO_that_remain_constant_no_matter_what_is_changing_in_the_technology_landscape_or_what_industry_you_are_serving_in\"><\/span>Para empezar, todos sabemos que la tecnolog\u00eda est\u00e1 cambiando a un ritmo vertiginoso, pero quiero ir un poco m\u00e1s all\u00e1 y preguntarles sobre la otra cara de la moneda. \u00bfCu\u00e1les creen que son las claves del \u00e9xito como CIO que permanecen constantes, independientemente de los cambios en el panorama tecnol\u00f3gico o del sector en el que trabajen?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Es un desaf\u00edo justo, porque el ritmo del cambio domina la conversaci\u00f3n. Pero cuando analizo qu\u00e9 hace que los CIO sean efectivos hoy en d\u00eda, cuatro cosas se repiten constantemente, y ninguna de ellas es nueva.<\/p>\n<p>El impacto en el negocio es el primero y m\u00e1s constante. Para m\u00ed, la tecnolog\u00eda suele ser un medio para un fin, no el fin en s\u00ed misma. La pregunta siempre es c\u00f3mo podemos ayudar a la organizaci\u00f3n a crecer, operar con mayor eficacia, brindar un mejor servicio a los clientes y gestionar el riesgo de forma m\u00e1s inteligente. Esta perspectiva no cambia con el panorama tecnol\u00f3gico.<\/p>\n<p>Estrechamente ligada a esto est\u00e1 la confianza. Las organizaciones necesitan l\u00edderes capaces de gestionar la complejidad, tomar decisiones acertadas y ser transparentes respecto a las ventajas y desventajas. Y para lograrlo, para obtener la credibilidad necesaria, se requiere confianza. Esto siempre ha sido as\u00ed, y no preveo que vaya a cambiar.<\/p>\n<p>Luego est\u00e1 la disciplina en la ejecuci\u00f3n, que a menudo se da por sentada. Se puede tener la mejor estrategia y visi\u00f3n, pero si no se puede ofrecer una ejecuci\u00f3n consistente y que aporte valor real, no sirve de nada. Esto aplica tanto a operaciones, ciberseguridad, IA generativa como al seguimiento de iniciativas empresariales.<\/p>\n<p>Y el aspecto que m\u00e1s me importa es el liderazgo de personas. No importa lo que haga la tecnolog\u00eda. En \u00faltima instancia, son las personas quienes lo hacen posible. Crear equipos s\u00f3lidos, desarrollar el talento, liderar en tiempos de cambio: estos siempre han sido pilares fundamentales de este rol. La tecnolog\u00eda cambia. Los fundamentos del liderazgo, en realidad, permanecen.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"You_describe_yourself_as_a_people-first_leader_and_have_said_that_people_are_the_heart_of_every_organization_That_is_maybe_something_of_an_unusual_posture_for_someone_in_a_role_so_often_reduced_to_systems_and_infrastructure_But_what_I_want_to_know_is_in_practical_terms_how_do_you_operate_as_a_people-first_CIO_What_do_you_do\"><\/span>Te describes como un l\u00edder que prioriza a las personas y has dicho que son el coraz\u00f3n de toda organizaci\u00f3n. Quiz\u00e1s sea una postura inusual para alguien que ocupa un puesto que a menudo se reduce a sistemas e infraestructura. Pero lo que quiero saber es, en t\u00e9rminos pr\u00e1cticos, \u00bfc\u00f3mo te desenvuelves como CIO que prioriza a las personas? \u00bfQu\u00e9 haces?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Para m\u00ed, priorizar a las personas no es un eslogan ni una filosof\u00eda. Es un principio fundamental. Se trata de c\u00f3mo te presentas cada d\u00eda.<\/p>\n<p>Y todo comienza, siempre, con escuchar. No escuchar para responder, sino para comprender y, luego, para ayudar. Hay que saber d\u00f3nde est\u00e1n los equipos, d\u00f3nde tienen problemas, d\u00f3nde hay fricci\u00f3n, d\u00f3nde faltan prioridades. No se puede llegar a eso por suposiciones. Esa es la base sobre la que se construye todo lo dem\u00e1s.<\/p>\n<p>A partir de ah\u00ed, se trata de crear el entorno adecuado. S\u00e9 que puede sonar a t\u00f3pico, pero para m\u00ed significa algo concreto. Significa tener claro hacia d\u00f3nde se dirigen las personas, darles autonom\u00eda sobre c\u00f3mo lograrlo y exigirles responsabilidad por su cometido. Cuando las personas saben de qu\u00e9 son responsables y se sienten capacitadas para hacerlo, la calidad del trabajo mejora. Se nota la diferencia. Todo el mundo la nota.<\/p>\n<p>El desarrollo del talento es una prioridad para el liderazgo y un pilar fundamental de una gesti\u00f3n centrada en las personas. Si bien las contrataciones externas aportan nuevas habilidades y perspectivas, los empleados actuales brindan un conocimiento empresarial, un contexto y una experiencia institucional invaluables que no se pueden reemplazar f\u00e1cilmente. Las organizaciones m\u00e1s s\u00f3lidas logran un equilibrio entre ambos: invierten en el crecimiento del talento interno y, al mismo tiempo, incorporan estrat\u00e9gicamente la experiencia externa. Al desarrollar a los empleados actuales y facilitar la r\u00e1pida integraci\u00f3n y contribuci\u00f3n de las nuevas contrataciones, las organizaciones construyen equipos m\u00e1s s\u00f3lidos y una reserva de talento m\u00e1s sostenible.<\/p>\n<p>Y luego est\u00e1 la dimensi\u00f3n humana, que creo que se subestima en las conversaciones sobre liderazgo tecnol\u00f3gico. Cuando uno entra en una organizaci\u00f3n y tiene que ser disruptivo, y en este entorno casi siempre lo es, a\u00fan puede hacerlo de una manera emp\u00e1tica, transparente y que ayude a la gente a comprender el porqu\u00e9. Porque, al fin y al cabo, las personas rinden al m\u00e1ximo cuando se sienten respetadas, apoyadas y conectadas con el prop\u00f3sito. Todos sabemos lo que se siente y todos sabemos cu\u00e1ndo falta.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Given_everything_that_is_happening_right_now_with_AI_agentic_systems_and_the_pace_of_change_more_broadly_what_are_you_doing_differently_as_a_leader_today_than_you_were_five_years_ago\"><\/span>Teniendo en cuenta todo lo que est\u00e1 sucediendo actualmente con la IA, los sistemas aut\u00f3nomos y el ritmo del cambio en general, \u00bfqu\u00e9 est\u00e1 haciendo usted de manera diferente como l\u00edder hoy en d\u00eda en comparaci\u00f3n con hace cinco a\u00f1os?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Lo que m\u00e1s he notado es el cambio en la importancia que se le da a la adaptabilidad y la velocidad de aprendizaje, y lo veo en todos los niveles. No hace mucho, se hac\u00eda m\u00e1s hincapi\u00e9 en si se contaba con la pila tecnol\u00f3gica adecuada y si se pod\u00eda ejecutar un plan. Eso ten\u00eda sentido cuando el panorama era m\u00e1s estable. Ahora, lo que importa m\u00e1s es si los l\u00edderes son curiosos, si est\u00e1n dispuestos a aprender y si pueden adaptarse, porque ya casi nada es fijo. La idea de que se puede dise\u00f1ar una arquitectura tecnol\u00f3gica y ce\u00f1irse a ella en gran medida se ha desvanecido.<\/p>\n<p>Actualmente, el canal est\u00e1 repleto de informaci\u00f3n irrelevante, lo que supone un verdadero desaf\u00edo para el liderazgo. \u00bfQu\u00e9 es real y qu\u00e9 no? Para discernir la verdad, se requiere concentraci\u00f3n. Es fundamental saber d\u00f3nde vale la pena profundizar y d\u00f3nde no, y hay que estructurar la experimentaci\u00f3n, ya que las pruebas, la escalabilidad y el aprendizaje son cruciales, pero solo si existe un marco que los cohesione. Se necesita espacio para la innovaci\u00f3n sin perder la disciplina que la hace viable.<\/p>\n<p>El cambio que he acogido con satisfacci\u00f3n es la mayor seriedad con la que se abordan la calidad y la gobernanza de los datos. Antes, estas conversaciones se recib\u00edan de forma muy distinta. Si mencionabas la gobernanza de datos, la gente se quedaba con la mirada perdida. Ahora, cuando la planteas, entienden inmediatamente por qu\u00e9 es importante, y eso es consecuencia directa de la evoluci\u00f3n de la IA. Porque, sinceramente, sin buenos datos, la IA no te aportar\u00e1 nada \u00fatil. Las organizaciones que han invertido en la calidad de los datos son las que pueden aprovechar estas capacidades. Si introduces datos err\u00f3neos, obtendr\u00e1s resultados err\u00f3neos, y ninguna herramienta sofisticada puede cambiar esa ecuaci\u00f3n.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Boards_are_appointing_more_CIOs_with_CS_degrees_and_deep_technical_backgrounds_and_fewer_with_traditional_MBA_profiles_Is_that_the_right_move_or_are_boards_potentially_making_a_mistake\"><\/span>Los consejos de administraci\u00f3n est\u00e1n nombrando a m\u00e1s directores de inform\u00e1tica con t\u00edtulos en ciencias de la computaci\u00f3n y una s\u00f3lida formaci\u00f3n t\u00e9cnica, y a menos con perfiles de MBA tradicionales. \u00bfEs esta la decisi\u00f3n correcta o podr\u00edan estar cometiendo un error?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>He reflexionado bastante sobre esto, incluso a partir de mi propia experiencia en consejos de administraci\u00f3n de empresas tanto p\u00fablicas como privadas. Y para m\u00ed, en realidad no es una opci\u00f3n.<\/p>\n<p>S\u00ed, un CIO necesita conocimientos t\u00e9cnicos s\u00f3lidos. Debe dominar la ciberseguridad, la arquitectura de datos, la estrategia de plataformas y las tendencias de las tecnolog\u00edas emergentes. Todo esto es fundamental. Sin embargo, la mera competencia t\u00e9cnica no garantiza un puesto en la alta direcci\u00f3n ni en el consejo de administraci\u00f3n. Tambi\u00e9n es necesario ser un l\u00edder empresarial. Hay que hablar el lenguaje del negocio y saber conectar lo que se hace t\u00e9cnicamente con lo que significa para la organizaci\u00f3n.<\/p>\n<p>El modelo al que siempre vuelvo es el del l\u00edder en forma de T. La vertical es su disciplina t\u00e9cnica, y s\u00ed, el CIO necesita tener una gran profundidad en ella. Pero para un CIO, la horizontal, la capacidad de trabajar en toda la organizaci\u00f3n y conectar la tecnolog\u00eda con el valor empresarial, es la parte m\u00e1s importante y exigente del puesto. Si solo se tiene la vertical, ser\u00e1 dif\u00edcil ser eficaz al nivel que exige este rol. Hay que ser biling\u00fce: t\u00e9cnico y empresarial. Y si no se tienen ambas, creo que ser\u00e1 muy dif\u00edcil tener el impacto que requiere el puesto.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"If_you_were_sitting_in_front_of_a_room_full_of_CEOs_and_board_members_what_would_you_tell_them_about_how_to_set_a_CIO_up_to_succeed_once_they_have_been_chosen\"><\/span>Si estuvieras sentado frente a una sala llena de directores ejecutivos y miembros de la junta directiva, \u00bfqu\u00e9 les dir\u00edas sobre c\u00f3mo preparar a un CIO para el \u00e9xito una vez que haya sido elegido?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Muchos CIOs acceden a puestos con un mandato demasiado vago o amplio para poder actuar. Las organizaciones que lo hacen bien ya lo han resuelto durante el proceso de selecci\u00f3n, incluso antes de hacer una oferta. Es fundamental tener claro el motivo de la contrataci\u00f3n. \u00bfEs para estabilizar las operaciones? \u00bfLiderar una transformaci\u00f3n? \u00bfModernizar el n\u00facleo? \u00bfImpulsar la adopci\u00f3n de la IA? \u00bfFortalecer la ciberresiliencia? Los CIOs casi siempre heredan una agenda amplia, y eso est\u00e1 bien, pero si desde el primer d\u00eda no hay claridad sobre qu\u00e9 significa el \u00e9xito, ya se ha complicado el trabajo innecesariamente. Y si no se tiene claro cu\u00e1l es el mandato, hay que ser transparente al respecto. Los mejores CIOs que conozco prefieren realizar su propia evaluaci\u00f3n antes que recibir un conjunto de prioridades que no se ajuste a la realidad.<\/p>\n<p>M\u00e1s all\u00e1 del mandato, reflexione detenidamente sobre si est\u00e1 tratando al CIO como un socio estrat\u00e9gico en la alta direcci\u00f3n o simplemente como alguien que se encarga de que todo funcione correctamente. Son relaciones muy diferentes. Involucrar al CIO desde el principio, cuando se consideran fusiones y adquisiciones, cuando se toman decisiones sobre el modelo operativo o cuando la estrategia a\u00fan se est\u00e1 definiendo, es completamente distinto a darle una respuesta a posteriori. Si desea que contribuya a definir los resultados, debe participar en la conversaci\u00f3n antes de que estos se decidan.<\/p>\n<p>Tambi\u00e9n est\u00e1 la cuesti\u00f3n de la autoridad, y creo que esta se subestima. Si se quiere que el CIO mejore la calidad de los datos, modernice las plataformas e impulse la adopci\u00f3n de la IA en toda la empresa, hay que otorgarle la autoridad necesaria para hacerlo. Un CIO no trabaja de forma aislada. Su funci\u00f3n es multifuncional y, en muchos sentidos, el CIO es el nexo de uni\u00f3n de toda la organizaci\u00f3n, la persona que comprende c\u00f3mo encaja todo. Para que esta persona sea eficaz, necesita la capacidad de impulsar el cambio en todas las funciones, no solo dentro del departamento de tecnolog\u00eda.<\/p>\n<p>Y si pudiera dejarles una idea clave, ser\u00eda que la tecnolog\u00eda representa solo el veinte por ciento del trabajo de un CIO. El otro ochenta por ciento consiste en liderazgo ejecutivo, impulsar el cambio interfuncional, lograr el consenso y alinear a las personas en toda la organizaci\u00f3n para asegurar que lo que se hace tenga sentido. La tecnolog\u00eda se implementa. El trabajo m\u00e1s arduo es el humano. Los consejos de administraci\u00f3n y los directores ejecutivos que comprendan esto preparar\u00e1n a sus CIO para el \u00e9xito. Quienes lo traten como un cargo puramente t\u00e9cnico seguir\u00e1n pregunt\u00e1ndose por qu\u00e9 no obtienen los resultados esperados.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>Conversaci\u00f3n con Madhuri Andrews, vicepresidenta ejecutiva y directora de inform\u00e1tica de MKS Inc., y miembro del consejo de administraci\u00f3n de Applied Industrial Technologies, Inc.<\/p>","protected":false},"author":1,"featured_media":146771,"template":"","interview-categories":[11365],"class_list":["post-146772","interviews","type-interviews","status-publish","has-post-thumbnail","hentry","interview-categories-technology-and-digital"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>People First Technology Leadership and CIO Success | N2Growth<\/title>\n<meta name=\"description\" content=\"Discover insights on people first technology leadership as Madhuri Andrews shares her CIO experiences and best practices.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.n2growth.com\/es_mx\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Madhuri Andrews on people-first technology leadership\" \/>\n<meta property=\"og:description\" content=\"Discover insights on people first technology leadership as Madhuri Andrews shares her CIO experiences and best practices.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.n2growth.com\/es_mx\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/\" \/>\n<meta property=\"og:site_name\" content=\"N2Growth\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/n2growth\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1084\" \/>\n\t<meta property=\"og:image:height\" content=\"1003\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@n2growth\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Liderazgo tecnol\u00f3gico centrado en las personas y \u00e9xito del CIO | N2Growth","description":"Descubra perspectivas sobre el liderazgo tecnol\u00f3gico centrado en las personas, de la mano de Madhuri Andrews, quien comparte sus experiencias como CIO y sus mejores pr\u00e1cticas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.n2growth.com\/es_mx\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/","og_locale":"es_MX","og_type":"article","og_title":"Madhuri Andrews on people-first technology leadership","og_description":"Discover insights on people first technology leadership as Madhuri Andrews shares her CIO experiences and best practices.","og_url":"https:\/\/www.n2growth.com\/es_mx\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/","og_site_name":"N2Growth","article_publisher":"https:\/\/www.facebook.com\/n2growth","og_image":[{"width":1084,"height":1003,"url":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@n2growth","twitter_misc":{"Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.n2growth.com\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/","url":"https:\/\/www.n2growth.com\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/","name":"Liderazgo tecnol\u00f3gico centrado en las personas y \u00e9xito del CIO | N2Growth","isPartOf":{"@id":"https:\/\/www.n2growth.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.n2growth.com\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/#primaryimage"},"image":{"@id":"https:\/\/www.n2growth.com\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/#primaryimage"},"thumbnailUrl":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews.jpg","datePublished":"2026-08-20T09:09:32+00:00","description":"Descubra perspectivas sobre el liderazgo tecnol\u00f3gico centrado en las personas, de la mano de Madhuri Andrews, quien comparte sus experiencias como CIO y sus mejores pr\u00e1cticas.","breadcrumb":{"@id":"https:\/\/www.n2growth.com\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.n2growth.com\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.n2growth.com\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/#primaryimage","url":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews.jpg","contentUrl":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews.jpg","width":1084,"height":1003,"caption":"A conversation with Madhuri Andrews, EVP and CIO at MKS Inc., and Board Director, Applied Industrial Technologies, Inc."},{"@type":"BreadcrumbList","@id":"https:\/\/www.n2growth.com\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.n2growth.com\/"},{"@type":"ListItem","position":2,"name":"Madhuri Andrews on people-first technology leadership"}]},{"@type":"WebSite","@id":"https:\/\/www.n2growth.com\/#website","url":"https:\/\/www.n2growth.com\/","name":"N2Growth","description":"Encontramos y desarrollamos los mejores l\u00edderes del mundo&#039;","publisher":{"@id":"https:\/\/www.n2growth.com\/#organization"},"alternateName":"N2 Growth","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.n2growth.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.n2growth.com\/#organization","name":"N2Growth","alternateName":"N2 Growth","url":"https:\/\/www.n2growth.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.n2growth.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2019\/05\/N2Growth-Logo-Dark.png","contentUrl":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2019\/05\/N2Growth-Logo-Dark.png","width":500,"height":142,"caption":"N2Growth"},"image":{"@id":"https:\/\/www.n2growth.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/n2growth","https:\/\/x.com\/n2growth","https:\/\/www.instagram.com\/n2growth","https:\/\/www.linkedin.com\/company\/n2growth","https:\/\/www.pinterest.com\/gon2growth\/","https:\/\/www.youtube.com\/c\/n2growth-"],"description":"Firma global de b\u00fasqueda de ejecutivos, coaching ejecutivo y asesor\u00eda de liderazgo","email":"press@n2growth.com","telephone":"+18009444662","legalName":"N2Growth Inc.","foundingDate":"2006-05-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}}]}},"_links":{"self":[{"href":"https:\/\/www.n2growth.com\/es_mx\/wp-json\/wp\/v2\/interviews\/146772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.n2growth.com\/es_mx\/wp-json\/wp\/v2\/interviews"}],"about":[{"href":"https:\/\/www.n2growth.com\/es_mx\/wp-json\/wp\/v2\/types\/interviews"}],"author":[{"embeddable":true,"href":"https:\/\/www.n2growth.com\/es_mx\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.n2growth.com\/es_mx\/wp-json\/wp\/v2\/media\/146771"}],"wp:attachment":[{"href":"https:\/\/www.n2growth.com\/es_mx\/wp-json\/wp\/v2\/media?parent=146772"}],"wp:term":[{"taxonomy":"interview-categories","embeddable":true,"href":"https:\/\/www.n2growth.com\/es_mx\/wp-json\/wp\/v2\/interview-categories?post=146772"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}