{"id":142714,"date":"2026-01-30T08:21:32","date_gmt":"2026-01-30T13:21:32","guid":{"rendered":"https:\/\/www.n2growth.com\/?post_type=interviews&#038;p=142714"},"modified":"2026-07-15T13:22:21","modified_gmt":"2026-07-15T17:22:21","slug":"the-kraft-heinz-companys-melissa-werneck-on-workforce-development","status":"publish","type":"interviews","link":"https:\/\/www.n2growth.com\/fr\/interviews\/the-kraft-heinz-companys-melissa-werneck-on-workforce-development\/","title":{"rendered":"Melissa Werneck, de Kraft Heinz Company, s&#039;exprime sur le d\u00e9veloppement de la main-d&#039;\u0153uvre"},"content":{"rendered":"<section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><img decoding=\"async\" class=\"alignleft wp-image-142521\" src=\"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/01\/Melissa-Werneck.png\" alt=\"\" width=\"230\" height=\"213\" \/><\/p>\n<p>Le d\u00e9veloppement de la main-d&#039;\u0153uvre peut facilement se transformer en un ensemble de programmes bien intentionn\u00e9s qui font bonne figure sur un tableau de bord, mais qui ne se traduisent jamais par des r\u00e9sultats concrets. <a href=\"https:\/\/www.linkedin.com\/in\/melissa-werneck-b89736\/\">Melissa Werneck<\/a> Elle a consacr\u00e9 sa carri\u00e8re \u00e0 lutter contre ce pi\u00e8ge. \u00c0 travers des r\u00f4les allant des ressources humaines aux op\u00e9rations en passant par la transformation \u00e0 grande \u00e9chelle, son leitmotiv est pragmatique\u00a0: le d\u00e9veloppement n\u2019a d\u2019int\u00e9r\u00eat que s\u2019il am\u00e9liore la capacit\u00e9 de l\u2019organisation \u00e0 mettre en \u0153uvre sa strat\u00e9gie.<\/p>\n<p>Melissa occupait le poste de directrice des ressources humaines chez Heinz, et plus tard <a href=\"https:\/\/www.kraftheinz.com\/\">Kraft Heinz<\/a>, pendant plus de 12 ans, dirigeant \u00e9galement les d\u00e9partements des technologies de l&#039;information et des services partag\u00e9s pendant 5 de ces 12 ann\u00e9es, une combinaison unique de fonctions.<\/p>\n<p>Apr\u00e8s avoir d\u00e9but\u00e9 sa carri\u00e8re comme ing\u00e9nieure chimiste dans le secteur industriel, Melissa s&#039;est orient\u00e9e vers les ressources humaines. Elle est reconnue pour son approche pragmatique du d\u00e9veloppement des comp\u00e9tences, de la planification de la rel\u00e8ve et de la transformation des entreprises. Bas\u00e9e dans la r\u00e9gion de Chicago, elle si\u00e8ge \u00e9galement aux conseils d&#039;administration de XP Inc. et de World Business Chicago.<\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2><span class=\"ez-toc-section\" id=\"To_begin_youve_built_and_led_workforce_development_at_scale_through_transformation_across_geographies_and_with_rare_cross-functional_scope_across_HR_IT_and_shared_services_Based_on_that_remarkably_wide_ranging_set_of_experiences_what_do_you_see_as_two_or_three_non-negotiables_every_CEO_and_CHRO_must_get_right_when_it_comes_to_workforce_development\"><\/span>Pour commencer, vous avez con\u00e7u et pilot\u00e9 des programmes de d\u00e9veloppement des effectifs \u00e0 grande \u00e9chelle, \u00e0 travers des transformations, dans diff\u00e9rentes r\u00e9gions g\u00e9ographiques et avec une vision transversale rare, englobant les RH, l&#039;informatique et les services partag\u00e9s. Fort de cette exp\u00e9rience remarquablement diversifi\u00e9e, quels sont selon vous deux ou trois imp\u00e9ratifs que tout PDG et DRH se doit de ma\u00eetriser en mati\u00e8re de d\u00e9veloppement des effectifs\u00a0?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Tout d&#039;abord, ouvrez-vous au monde ext\u00e9rieur. Ne perdez pas de vue ce que signifie l&#039;excellence. Il est facile de s&#039;enorgueillir des initiatives mises en \u0153uvre, surtout apr\u00e8s des succ\u00e8s pass\u00e9s. Mais c&#039;est alors qu&#039;on s&#039;enferme dans sa propre bulle. J&#039;encourage toujours les dirigeants \u00e0 dialoguer avec d&#039;autres organisations et d&#039;autres secteurs, afin de comparer et d&#039;am\u00e9liorer constamment leurs pratiques et de pr\u00e9parer l&#039;avenir.<\/p>\n<p>Un aspect essentiel est de d\u00e9mocratiser l&#039;apprentissage. Les formations intensives et les programmes sur mesure sont utiles, mais \u00e0 eux seuls, ils ne stimulent pas la curiosit\u00e9. En rendant l&#039;apprentissage accessible \u00e0 tous les employ\u00e9s, quel que soit leur fuseau horaire, leur fonction ou leur niveau hi\u00e9rarchique, on les incite \u00e0 puiser des connaissances dans diverses sources et \u00e0 repenser leurs pratiques quotidiennes. C&#039;est ainsi que l&#039;on d\u00e9veloppe une vision strat\u00e9gique \u00e0 l&#039;\u00e9chelle de l&#039;entreprise, et non une simple expertise pointue au sein d&#039;une fonction.<\/p>\n<p>Deuxi\u00e8mement, anticipez l&#039;avenir et affirmez vos priorit\u00e9s. J&#039;encourage les \u00e9quipes \u00e0 faire une pause et \u00e0 se demander\u00a0: \u201c\u00a0De quoi aurons-nous besoin ensuite, et comment pouvons-nous y r\u00e9pondre d\u00e8s maintenant\u00a0?\u00a0\u201d Si vous ne construisez que pour le pr\u00e9sent, vous arriverez plus tard \u00e0 un monde qui aura de nouveau chang\u00e9, et vous serez en train de rattraper votre retard. Et lorsque vous choisissez o\u00f9 investir, ne dispersez pas vos ressources sur des centaines de fonctionnalit\u00e9s superflues. Concentrez-vous sur les capacit\u00e9s essentielles \u00e0 votre strat\u00e9gie, puis engagez-vous pleinement \u00e0 les d\u00e9velopper d&#039;une mani\u00e8re qui vous distingue v\u00e9ritablement.<\/p>\n<p>Enfin, consid\u00e9rez la transformation comme un processus continu, et non comme un projet ponctuel. La transformation ne se fait pas du jour au lendemain. Elle exige patience, pers\u00e9v\u00e9rance et r\u00e9silience. Nombre d&#039;organisations cr\u00e9ent un bureau de la transformation pour une courte p\u00e9riode, mettent en \u0153uvre quelques mesures et crient victoire. Or, la r\u00e9alit\u00e9 est tout autre. On transforme quelque chose aujourd&#039;hui, et demain, on en transforme autre chose. La capacit\u00e9 \u00e0 d\u00e9velopper est celle du renouvellement continu.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"From_a_board_or_CEO_perspective_%E2%80%9Cdevelopment%E2%80%9D_can_feel_intangible_How_did_you_make_your_workforce_transformation_measurable_and_board-visible_What_would_you_tell_CHROs_at_the_start_of_a_development_transformation_about_ways_to_translate_the_progress_being_made_into_metrics_and_proof_points_that_boards_and_CEOs_can_consistently_track_And_what_might_be_warning_signs_that_an_effort_is_becoming_performative_rather_than_embedded\"><\/span>Du point de vue d&#039;un conseil d&#039;administration ou d&#039;un PDG, le \u201c\u00a0d\u00e9veloppement\u00a0\u201d peut sembler abstrait. Comment avez-vous rendu la transformation de vos effectifs mesurable et visible pour le conseil d&#039;administration\u00a0? Que conseilleriez-vous aux DRH au d\u00e9but d&#039;une transformation ax\u00e9e sur le d\u00e9veloppement, concernant la mani\u00e8re de traduire les progr\u00e8s accomplis en indicateurs et en preuves tangibles que les conseils d&#039;administration et les PDG peuvent suivre de mani\u00e8re constante\u00a0? Et quels sont les signes avant-coureurs indiquant qu&#039;une d\u00e9marche devient purement formelle plut\u00f4t qu&#039;int\u00e9gr\u00e9e\u00a0?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Pour moi, c&#039;est simple. Si l&#039;entreprise ne produit pas de r\u00e9sultats concrets, ou si vous ne constatez pas d&#039;am\u00e9lioration \u00e0 court terme, vos initiatives sont inefficaces. L&#039;objectif ultime est de mettre en \u0153uvre la strat\u00e9gie. Si vous n&#039;y parvenez pas, le d\u00e9veloppement se r\u00e9duit \u00e0 une simple activit\u00e9 au lieu d&#039;avoir un impact concret.<\/p>\n<p>C&#039;est pourquoi j&#039;appr\u00e9cie les m\u00e9canismes d&#039;\u00e9coute qui permettent de v\u00e9rifier si les comp\u00e9tences se manifestent concr\u00e8tement dans le travail. Les enqu\u00eates d&#039;engagement en sont un exemple, et j&#039;\u00e9largirais cette approche aux boucles de r\u00e9troaction avec les parties prenantes internes et externes. Si vous investissez dans le d\u00e9veloppement du leadership et que les employ\u00e9s affirment ne pas recevoir de retour d&#039;information ad\u00e9quat, ou que leurs managers ne les aident pas \u00e0 donner le meilleur d&#039;eux-m\u00eames au travail, alors votre programme n&#039;atteint pas ses objectifs. Si vous investissez dans un ensemble de comp\u00e9tences et que les parties prenantes ne constatent aucune am\u00e9lioration, alors votre investissement est inefficace.<\/p>\n<p>Le probl\u00e8me des dirigeants, c&#039;est qu&#039;ils s&#039;appuient sur des indicateurs traditionnels dont le sens n&#039;est plus le m\u00eame. J&#039;ai vu des responsables de la formation mettre en avant des notions comme \u201c\u00a0heures de formation\u00a0\u201d, \u201c\u00a0budget par employ\u00e9\u00a0\u201d et des comparaisons avec des normes \u00e9tablies. Ces mesures ne sont plus pertinentes. On apprend de multiples fa\u00e7ons, notamment en lisant et en pratiquant directement dans son travail. Il vaut mieux commencer par clarifier la raison d&#039;\u00eatre d&#039;un programme. En testant la robustesse de vos objectifs, vous d\u00e9finirez plus facilement les crit\u00e8res de r\u00e9ussite. Vous pourrez ensuite choisir un ou deux indicateurs simples pour ajuster votre travail au fil du temps.<\/p>\n<p>Attention\u00a0: augmenter les d\u00e9penses n\u2019est pas une garantie de succ\u00e8s. En r\u00e9alit\u00e9, si vous parvenez \u00e0 d\u00e9velopper plus efficacement tout en d\u00e9pensant moins, c\u2019est un avantage. Les indicateurs deviennent de simples indicateurs de performance lorsqu\u2019ils valorisent les efforts plut\u00f4t que les r\u00e9sultats. Le signal d\u2019alarme est une am\u00e9lioration du tableau de bord, mais une stagnation des r\u00e9sultats commerciaux et de l\u2019exp\u00e9rience des employ\u00e9s.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"You_began_your_career_as_a_chemical_engineer_in_manufacturing_a_different_starting_point_than_many_corporate_leaders_have_What_did_starting_there_teach_you_about_what_creates_real_growth_at_the_beginning_of_a_career_and_how_has_it_shaped_the_way_you_design_or_evaluate_leadership_development\"><\/span>Vous avez d\u00e9but\u00e9 votre carri\u00e8re comme ing\u00e9nieur chimiste dans le secteur manufacturier, un point de d\u00e9part atypique pour un dirigeant d&#039;entreprise. Qu&#039;avez-vous appris de cette exp\u00e9rience quant aux facteurs de v\u00e9ritable progression en d\u00e9but de carri\u00e8re, et comment a-t-elle influenc\u00e9 votre approche du d\u00e9veloppement du leadership\u00a0?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La raison pour laquelle j&#039;ai choisi le g\u00e9nie chimique est la m\u00eame que celle qui m&#039;a ensuite pouss\u00e9e \u00e0 choisir les RH\u00a0: la transformation. J&#039;ai toujours \u00e9t\u00e9 fascin\u00e9e par l&#039;id\u00e9e qu&#039;une mati\u00e8re premi\u00e8re puisse se m\u00e9tamorphoser. \u00c0 cinq ans, j&#039;avais construit ce que je croyais \u00eatre une usine \u00e0 shampoing dans ma salle de bain. Ma m\u00e8re soutenait mes exp\u00e9riences \u00e0 une seule condition\u00a0: interdiction de tester le shampoing sur mes cheveux ou ceux du chien. Cette curiosit\u00e9 ne m&#039;a jamais quitt\u00e9e. En RH, j&#039;adore accompagner les personnes dans leur transformation. Mes plus grandes joies sont celles o\u00f9 quelqu&#039;un m&#039;annonce avoir obtenu une promotion, re\u00e7u des retours constructifs ou appliqu\u00e9 un coaching de mani\u00e8re \u00e0 r\u00e9ussir.<\/p>\n<p>Ces premi\u00e8res ann\u00e9es sur le terrain m&#039;ont aussi appris l&#039;humilit\u00e9 et ont fa\u00e7onn\u00e9 ma fa\u00e7on de diriger aujourd&#039;hui. En tant que stagiaire, j&#039;ai travaill\u00e9 en \u00e9troite collaboration avec les op\u00e9rateurs, y compris ceux qui avaient un niveau de formation moins \u00e9lev\u00e9 que le mien. J&#039;ai \u00e9norm\u00e9ment appris car je n&#039;ai jamais abord\u00e9 le travail en pr\u00e9tendant d\u00e9tenir la v\u00e9rit\u00e9 absolue. Je n&#039;ai pas impos\u00e9 ma m\u00e9thode. Je me suis sinc\u00e8rement int\u00e9ress\u00e9 aux gens, au-del\u00e0 de leur fonction, ce qui a instaur\u00e9 un climat de confiance. Ils souhaitaient ma r\u00e9ussite. Cette exp\u00e9rience est devenue le fondement de ma conception actuelle du leadership\u00a0: le caract\u00e8re, le respect et la capacit\u00e9 d&#039;apprendre avec les autres, et non pas seulement de briller en public.<\/p>\n<p>Le service des op\u00e9rations m&#039;a aussi appris \u00e0 \u201c\u00a0manager en \u00e9tant sur le terrain\u00a0\u201d. Rien ne se passe \u00e0 son bureau. On peut lire un e-mail et conclure une affaire, mais pour prendre des d\u00e9cisions \u00e9clair\u00e9es, il faut aller \u00e0 la source. Plus on \u00e9volue au sein d&#039;une organisation, plus l&#039;information est filtr\u00e9e. C&#039;est en voyant de ses propres yeux qu&#039;on peut se forger sa propre opinion. J&#039;ai beaucoup voyag\u00e9 et pass\u00e9 du temps avec les \u00e9quipes locales pour comprendre la culture, les besoins et les obstacles, car c&#039;est l\u00e0 que se trouvent les opportunit\u00e9s. C&#039;est aussi l\u00e0 que la progression de carri\u00e8re en d\u00e9but de parcours devient concr\u00e8te.<\/p>\n<p>Enfin, je dis toujours aux stagiaires que la vie n&#039;est pas lin\u00e9aire. Il faut savoir saisir les opportunit\u00e9s. Je pensais avoir toute ma carri\u00e8re planifi\u00e9e \u00e0 la sortie de mes \u00e9tudes. Les ressources humaines n&#039;en faisaient pas partie. Quelqu&#039;un a d\u00e9cel\u00e9 une opportunit\u00e9, m&#039;a propos\u00e9 une mission et j&#039;ai accept\u00e9. Si je n&#039;avais pas \u00e9t\u00e9 aussi ouverte aux nouveaut\u00e9s, mon parcours aurait \u00e9t\u00e9 bien diff\u00e9rent.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"If_AI_as_many_predict_shrinks_the_availability_of_entry_level_roles_and_organizations_become_less_of_a_pyramid_and_more_of_a_%E2%80%9Ctower%E2%80%9D_what_happens_to_leadership_pipelines_over_the_next_five_to_ten_years_As_that_entry_point_narrows_how_can_companies_be_proactive_Where_and_how_do_they_need_to_rethink_entry_level_hiring_and_selection_How_does_the_required_development_investment_per_hire_change_and_in_what_way_does_the_focus_and_nature_of_early_career_development_evolve\"><\/span>Si l&#039;IA, comme beaucoup le pr\u00e9voient, r\u00e9duit le nombre de postes de d\u00e9butant disponibles et que les organisations adoptent une structure moins pyramidale et plus verticale, qu&#039;adviendra-t-il des viviers de talents au cours des cinq \u00e0 dix prochaines ann\u00e9es\u00a0? Face \u00e0 cette rar\u00e9faction des opportunit\u00e9s d&#039;acc\u00e8s aux postes, comment les entreprises peuvent-elles anticiper\u00a0? O\u00f9 et comment doivent-elles repenser le recrutement et la s\u00e9lection des jeunes dipl\u00f4m\u00e9s\u00a0? Comment \u00e9voluera l&#039;investissement n\u00e9cessaire en formation par recrue, et comment la nature et l&#039;orientation du d\u00e9veloppement des jeunes talents \u00e9volueront-elles\u00a0?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Je pense qu&#039;il est essentiel de tirer des le\u00e7ons du pass\u00e9. Ce n&#039;est pas la premi\u00e8re r\u00e9volution qui bouleverse les m\u00e9thodes de travail. On a ressenti la m\u00eame chose lors de la g\u00e9n\u00e9ralisation des ordinateurs personnels dans les entreprises. Les organisations les plus performantes sont celles qui anticipent et mettent en \u0153uvre plus t\u00f4t des strat\u00e9gies cibl\u00e9es, notamment en mati\u00e8re de succession et de d\u00e9veloppement du leadership.<\/p>\n<p>La plupart des entreprises consacrent beaucoup de temps \u00e0 r\u00e9fl\u00e9chir \u00e0 la succession de leurs dirigeants. Dans un monde hi\u00e9rarchis\u00e9, il est essentiel d&#039;anticiper. Concr\u00e8tement, cela signifie que le recrutement de jeunes dipl\u00f4m\u00e9s vise moins \u00e0 pourvoir un poste qu&#039;\u00e0 s\u00e9lectionner des talents \u00e0 fort potentiel \u00e0 long terme. J&#039;ai vu des entreprises y parvenir avec succ\u00e8s en recrutant des stagiaires, des jeunes dipl\u00f4m\u00e9s et des titulaires de MBA pour leur potentiel de leadership, et non pour un poste pr\u00e9cis. Elles maintiennent ainsi une politique de recrutement stable, quelles que soient les circonstances, car elles recrutent d\u00e8s aujourd&#039;hui pour les profils dont elles auront besoin dans cinq \u00e0 dix ans, et elles d\u00e9veloppent les comp\u00e9tences de leurs collaborateurs sur toute cette p\u00e9riode.<\/p>\n<p>Une autre cons\u00e9quence est que les parcours de succession traditionnels, bas\u00e9s sur le temps, ne seront plus aussi efficaces. L&#039;id\u00e9e qu&#039;une personne doive passer X ann\u00e9es dans le domaine A, puis X ann\u00e9es dans le domaine B, puis X ann\u00e9es dans le domaine C suppose que l&#039;on dispose de beaucoup de temps. Or, de nombreuses organisations n&#039;en disposent pas. Il vous faudra des exp\u00e9riences plus rapides, permettant d&#039;acqu\u00e9rir des comp\u00e9tences par le travail concret. C&#039;est pourquoi j&#039;appr\u00e9cie les m\u00e9thodes de travail agiles. On apprend en travaillant sur des projets o\u00f9 l&#039;on est tant\u00f4t leader, tant\u00f4t suiveur. Cela favorise un leadership situationnel et d\u00e9veloppe l&#039;humilit\u00e9. Cela acc\u00e9l\u00e8re \u00e9galement le d\u00e9veloppement des comp\u00e9tences, car les individus pratiquent dans des contextes vari\u00e9s.<\/p>\n<p>Le changement le plus important, cependant, r\u00e9side dans le moment o\u00f9 le d\u00e9veloppement du leadership d\u00e9bute. Traditionnellement, les organisations attendent qu&#039;un employ\u00e9 devienne manager pour initier ce d\u00e9veloppement. \u00c0 mon avis, c&#039;est trop tard. La th\u00e9orie est importante, certes, mais le leadership ne s&#039;apprend pas uniquement dans les livres. Il s&#039;acquiert en traversant des situations difficiles, en g\u00e9rant les conflits et en menant des conversations franches. Si l&#039;IA r\u00e9duit le nombre de postes \u00e0 pourvoir, le d\u00e9veloppement du leadership risque d&#039;\u00eatre le domaine le plus touch\u00e9, \u00e0 moins que les PDG et les DRH ne le prot\u00e8gent et ne le mettent en place plus t\u00f4t, lorsque les employ\u00e9s sont encore des contributeurs individuels.<\/p>\n<p>Une statistique m&#039;a particuli\u00e8rement marqu\u00e9 : une \u00e9tude Gallup sugg\u00e8re qu&#039;une personne sur dix seulement poss\u00e8de un profil naturellement dou\u00e9 pour le management. De quoi donner des sueurs froides aux dirigeants ! On ne trouve pas que des personnes exceptionnelles. Il faut investir du temps et de l&#039;argent pour former les talents exceptionnels. Et si l&#039;on commence trop tard, les candidats n&#039;auront pas acquis suffisamment d&#039;exp\u00e9rience pour d\u00e9velopper les comp\u00e9tences n\u00e9cessaires \u00e0 la gestion des conflits et aux conversations difficiles, pourtant essentielles aux postes de direction. C&#039;est pourquoi la s\u00e9lection et le d\u00e9veloppement sont primordiaux en amont, bien avant l&#039;obtention du premier poste de manager.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Last_in_an_AI-shaped_economy_what_are_the_three_moves_you_would_recommend_CEOs_and_boards_make_in_the_next_12_to_24_months_to_reduce_talent_and_capability_risk_while_strengthening_the_leadership_pipeline_What_risks_do_leaders_most_often_underestimate_and_what_early_warning_signals_would_you_monitor_to_catch_problems_before_they_show_up_in_succession_gaps_or_performance\"><\/span>Enfin, dans une \u00e9conomie fa\u00e7onn\u00e9e par l&#039;IA, quelles sont les trois mesures que vous recommanderiez aux PDG et aux conseils d&#039;administration de prendre au cours des 12 \u00e0 24 prochains mois pour r\u00e9duire les risques li\u00e9s aux talents et aux comp\u00e9tences tout en renfor\u00e7ant le vivier de futurs dirigeants\u00a0? Quels sont les risques que les dirigeants sous-estiment le plus souvent, et quels signaux d&#039;alerte pr\u00e9coce surveilleriez-vous pour d\u00e9celer les probl\u00e8mes avant qu&#039;ils ne se traduisent par des lacunes dans la succession ou une baisse de performance\u00a0?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Adoptez tout d&#039;abord une approche ax\u00e9e sur la valorisation des talents. La finance alloue quotidiennement des capitaux en fonction de la valeur attendue. Les dirigeants devraient appliquer la m\u00eame logique au placement des talents. Certains postes peuvent para\u00eetre modestes aujourd&#039;hui, mais c&#039;est de ceux-ci que vous anticipez la plus forte croissance au cours des cinq prochaines ann\u00e9es. Vos meilleurs talents doivent donc y \u00eatre. Cela peut sembler paradoxal, car les syst\u00e8mes de r\u00e9mun\u00e9ration valorisent souvent l&#039;envergure et la port\u00e9e des projets, or la strat\u00e9gie ne suit pas toujours l&#039;organigramme. Il n&#039;est pas n\u00e9cessaire de tout repenser. Il est essentiel de se concentrer sur les quelques r\u00f4les qui contribuent r\u00e9ellement \u00e0 l&#039;obtention de r\u00e9sultats.<\/p>\n<p>Deuxi\u00e8mement, identifiez les 30 \u00e0 50 r\u00f4les qui contribueront de mani\u00e8re significative \u00e0 votre strat\u00e9gie, puis g\u00e9rez-les avec une grande pr\u00e9cision. D&#039;apr\u00e8s mon exp\u00e9rience, il s&#039;agit souvent d&#039;un petit nombre de r\u00f4les capables de g\u00e9n\u00e9rer 70 \u00e0 75 % de la valeur strat\u00e9gique. Pour ces r\u00f4les, inutile de lister 30 comp\u00e9tences ou une centaine de responsabilit\u00e9s. Concentrez-vous sur les quelques t\u00e2ches \u00e0 accomplir, puis d\u00e9finissez les deux ou trois comp\u00e9tences cl\u00e9s et exp\u00e9riences requises. Ensuite, \u00e9valuez les profils des candidats en fonction de ces exigences. Ces r\u00f4les ne sont pas un terrain d&#039;exp\u00e9rimentation. Vous avez de nombreux autres r\u00f4les o\u00f9 d\u00e9velopper les talents. Pour les r\u00f4les qui pilotent la strat\u00e9gie, il vous faut le bon leader, la bonne \u00e9quipe et un plan de succession auquel vous croyez.<\/p>\n<p>Troisi\u00e8mement, il est essentiel de d\u00e9finir clairement le mod\u00e8le op\u00e9rationnel d&#039;une IA g\u00e9n\u00e9rative responsable et d&#039;en faire une comp\u00e9tence de leadership, et non une simple politique technologique. Le train est d\u00e9j\u00e0 en marche. Tout le monde l&#039;utilise. On le constate m\u00eame \u00e0 l&#039;\u00e9cole, o\u00f9 certains enseignants l&#039;int\u00e8grent en d\u00e9finissant des r\u00e8gles d&#039;utilisation, tandis que d&#039;autres tentent de l&#039;interdire. Pour moi, \u201c\u00a0l&#039;interdire\u00a0\u201d revient \u00e0 dire qu&#039;on ne peut pas utiliser une calculatrice. L&#039;outil existe, il faut donc enseigner son utilisation responsable. Les conseils d&#039;administration et les directions g\u00e9n\u00e9rales doivent aborder ce sujet. Les dirigeants doivent \u00eatre des ambassadeurs d&#039;une mise en \u0153uvre responsable et placer l&#039;humain au c\u0153ur du processus, car l&#039;IA doit am\u00e9liorer la prise de d\u00e9cision, et non se substituer \u00e0 la responsabilit\u00e9. Il y a toujours quelqu&#039;un qui appuie sur le bouton de d\u00e9marrage.<\/p>\n<p>L&#039;erreur la plus fr\u00e9quente des responsables de la gestion des risques est de confondre potentiel et pr\u00e9paration, surtout pour les postes strat\u00e9giques. L&#039;agilit\u00e9 d&#039;apprentissage est certes pr\u00e9cieuse, mais insuffisante. Certaines exp\u00e9riences exigent de l&#039;exp\u00e9rience et une confrontation concr\u00e8te aux crises, aux n\u00e9gociations difficiles et aux choix corn\u00e9liens. Confier un r\u00f4le cl\u00e9 \u00e0 une personne n&#039;ayant jamais \u00e9t\u00e9 confront\u00e9e \u00e0 de telles situations repr\u00e9sente un risque, aussi rapide soit son apprentissage.<\/p>\n<p>Les premiers signaux d&#039;alerte sont g\u00e9n\u00e9ralement visibles avant que les performances ne s&#039;effondrent. Soyez attentif \u00e0 tout manque d&#039;impact sur l&#039;activit\u00e9 li\u00e9 \u00e0 vos investissements en d\u00e9veloppement. Surveillez l&#039;engagement et les retours des parties prenantes afin de d\u00e9celer des signes persistants indiquant que les managers ne donnent pas de v\u00e9ritables retours, \u00e9vitent les conflits ou n\u00e9gligent le d\u00e9veloppement de leurs collaborateurs. \u00c9valuez la solidit\u00e9 des listes de succession pour les postes \u00e0 haute valeur ajout\u00e9e, et pas seulement pour les plus hauts dirigeants. Enfin, assurez-vous que l&#039;organisation puisse accepter des d\u00e9cisions personnalis\u00e9es sans rompre la confiance. Lorsque certains r\u00f4les b\u00e9n\u00e9ficient de ressources, de pouvoirs de d\u00e9cision ou de r\u00e9mun\u00e9rations diff\u00e9rents en raison des exigences strat\u00e9giques, les dirigeants doivent en expliquer clairement la logique. Dans le cas contraire, l&#039;organisation rejettera le mod\u00e8le au lieu de l&#039;appliquer.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>Une conversation avec Melissa Werneck, conseill\u00e8re principale et ancienne vice-pr\u00e9sidente ex\u00e9cutive et directrice mondiale des ressources humaines de The Kraft Heinz Company.\u00a0<\/p>","protected":false},"author":1,"featured_media":142715,"template":"","interview-categories":[11364],"class_list":["post-142714","interviews","type-interviews","status-publish","has-post-thumbnail","hentry","interview-categories-people-and-culture"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Melissa Werneck on workforce development<\/title>\n<meta name=\"description\" content=\"A conversation with Melissa Werneck on workforce development, ensuring programs translate into real organizational performance.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.n2growth.com\/fr\/interviews\/the-kraft-heinz-companys-melissa-werneck-on-workforce-development\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Kraft Heinz Company\u2019s Melissa Werneck on workforce development\" \/>\n<meta property=\"og:description\" content=\"A conversation with Melissa Werneck on workforce development, ensuring programs translate into real organizational performance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.n2growth.com\/fr\/interviews\/the-kraft-heinz-companys-melissa-werneck-on-workforce-development\/\" \/>\n<meta property=\"og:site_name\" content=\"N2Growth\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/n2growth\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T17:22:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/01\/Melissa-Werneck.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1084\" \/>\n\t<meta property=\"og:image:height\" content=\"1003\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@n2growth\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Melissa Werneck sur le d\u00e9veloppement de la main-d&#039;\u0153uvre","description":"Une conversation avec Melissa Werneck sur le d\u00e9veloppement de la main-d&#039;\u0153uvre et comment garantir que les programmes se traduisent par une performance organisationnelle r\u00e9elle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.n2growth.com\/fr\/interviews\/the-kraft-heinz-companys-melissa-werneck-on-workforce-development\/","og_locale":"fr_FR","og_type":"article","og_title":"The Kraft Heinz Company\u2019s Melissa Werneck on workforce development","og_description":"A conversation with Melissa Werneck on workforce development, ensuring programs translate into real organizational performance.","og_url":"https:\/\/www.n2growth.com\/fr\/interviews\/the-kraft-heinz-companys-melissa-werneck-on-workforce-development\/","og_site_name":"N2Growth","article_publisher":"https:\/\/www.facebook.com\/n2growth","article_modified_time":"2026-07-15T17:22:21+00:00","og_image":[{"width":1084,"height":1003,"url":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/01\/Melissa-Werneck.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@n2growth","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.n2growth.com\/interviews\/the-kraft-heinz-companys-melissa-werneck-on-workforce-development\/","url":"https:\/\/www.n2growth.com\/interviews\/the-kraft-heinz-companys-melissa-werneck-on-workforce-development\/","name":"Melissa Werneck sur le d\u00e9veloppement de la main-d&#039;\u0153uvre","isPartOf":{"@id":"https:\/\/www.n2growth.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.n2growth.com\/interviews\/the-kraft-heinz-companys-melissa-werneck-on-workforce-development\/#primaryimage"},"image":{"@id":"https:\/\/www.n2growth.com\/interviews\/the-kraft-heinz-companys-melissa-werneck-on-workforce-development\/#primaryimage"},"thumbnailUrl":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/01\/Melissa-Werneck.png","datePublished":"2026-01-30T13:21:32+00:00","dateModified":"2026-07-15T17:22:21+00:00","description":"Une conversation avec Melissa Werneck sur le d\u00e9veloppement de la main-d&#039;\u0153uvre et comment garantir que les programmes se traduisent par une performance organisationnelle r\u00e9elle.","breadcrumb":{"@id":"https:\/\/www.n2growth.com\/interviews\/the-kraft-heinz-companys-melissa-werneck-on-workforce-development\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.n2growth.com\/interviews\/the-kraft-heinz-companys-melissa-werneck-on-workforce-development\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.n2growth.com\/interviews\/the-kraft-heinz-companys-melissa-werneck-on-workforce-development\/#primaryimage","url":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/01\/Melissa-Werneck.png","contentUrl":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/01\/Melissa-Werneck.png","width":1084,"height":1003},{"@type":"BreadcrumbList","@id":"https:\/\/www.n2growth.com\/interviews\/the-kraft-heinz-companys-melissa-werneck-on-workforce-development\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.n2growth.com\/"},{"@type":"ListItem","position":2,"name":"The Kraft Heinz Company\u2019s Melissa Werneck on workforce development"}]},{"@type":"WebSite","@id":"https:\/\/www.n2growth.com\/#website","url":"https:\/\/www.n2growth.com\/","name":"N2Growth","description":"Nous trouvons et d\u00e9veloppons les meilleurs leaders du monde","publisher":{"@id":"https:\/\/www.n2growth.com\/#organization"},"alternateName":"N2 Growth","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.n2growth.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.n2growth.com\/#organization","name":"N2Growth","alternateName":"N2 Growth","url":"https:\/\/www.n2growth.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.n2growth.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2019\/05\/N2Growth-Logo-Dark.png","contentUrl":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2019\/05\/N2Growth-Logo-Dark.png","width":500,"height":142,"caption":"N2Growth"},"image":{"@id":"https:\/\/www.n2growth.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/n2growth","https:\/\/x.com\/n2growth","https:\/\/www.instagram.com\/n2growth","https:\/\/www.linkedin.com\/company\/n2growth","https:\/\/www.pinterest.com\/gon2growth\/","https:\/\/www.youtube.com\/c\/n2growth-"],"description":"Cabinet international de recrutement de cadres, de coaching ex\u00e9cutif et de conseil en leadership","email":"press@n2growth.com","telephone":"+18009444662","legalName":"N2Growth Inc.","foundingDate":"2006-05-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}}]}},"_links":{"self":[{"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/interviews\/142714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/interviews"}],"about":[{"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/types\/interviews"}],"author":[{"embeddable":true,"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/media\/142715"}],"wp:attachment":[{"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/media?parent=142714"}],"wp:term":[{"taxonomy":"interview-categories","embeddable":true,"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/interview-categories?post=142714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}