{"id":145026,"date":"2026-06-24T11:19:29","date_gmt":"2026-06-24T15:19:29","guid":{"rendered":"https:\/\/www.n2growth.com\/?post_type=interviews&#038;p=145026"},"modified":"2026-07-15T10:10:16","modified_gmt":"2026-07-15T14:10:16","slug":"joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today","status":"publish","type":"interviews","link":"https:\/\/www.n2growth.com\/fr\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/","title":{"rendered":"Joshua Foltz, ancien RSSI de NerdWallet, nous explique ce qu&#039;il faut pour diriger la s\u00e9curit\u00e9 aujourd&#039;hui."},"content":{"rendered":"<section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><img decoding=\"async\" class=\"alignleft wp-image-145027\" src=\"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz-300x278.jpg\" alt=\"Entretien avec Joshua Foltz, ancien CISO chez NerdWallet\" width=\"230\" height=\"213\" srcset=\"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz-300x278.jpg 300w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz-1024x947.jpg 1024w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz-13x12.jpg 13w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz-150x139.jpg 150w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz.jpg 1084w\" sizes=\"(max-width: 230px) 100vw, 230px\" \/><\/p>\n<p>Le r\u00f4le du RSSI \u00e9volue rapidement, et les conseils d&#039;administration s&#039;interrogent \u00e0 juste titre sur l&#039;impact de cette \u00e9volution sur leurs recrutements. Dans cette discussion, <a href=\"https:\/\/www.linkedin.com\/in\/joshuafoltz\/\">Joshua Foltz<\/a> Cet ouvrage d\u00e9montre qu&#039;un leadership efficace en mati\u00e8re de s\u00e9curit\u00e9 exige autant de comp\u00e9tences commerciales que de connaissances techniques approfondies, explique pourquoi l&#039;IA est l&#039;arme la plus puissante dont l&#039;industrie de la s\u00e9curit\u00e9 ait jamais dispos\u00e9 et soutient que la cr\u00e9ativit\u00e9 et l&#039;adaptabilit\u00e9 sont les qualit\u00e9s que les conseils d&#039;administration doivent privil\u00e9gier dans la recherche d&#039;un RSSI capable de les diriger dans un environnement technologique en constante \u00e9volution.<\/p>\n<p>Joshua Foltz est un cadre dirigeant sp\u00e9cialis\u00e9 en cybers\u00e9curit\u00e9 et en intelligence artificielle, poss\u00e9dant plus de vingt ans d&#039;exp\u00e9rience dans les secteurs de la fintech, de l&#039;insurtech, du SaaS et des technologies r\u00e9glement\u00e9es, notamment son poste le plus r\u00e9cent de RSSI chez <a href=\"https:\/\/www.nerdwallet.com\/\">NerdPortefeuille<\/a>. Il est titulaire d&#039;un MBA de Yale et a b\u00e2ti sa carri\u00e8re \u00e0 l&#039;intersection de la s\u00e9curit\u00e9, de la gouvernance de l&#039;IA et de la transformation des entreprises.<\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2><span class=\"ez-toc-section\" id=\"How_do_you_think_about_where_the_CISO_role_is_heading\"><\/span>Comment voyez-vous l&#039;\u00e9volution du r\u00f4le de RSSI ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Pour les entreprises qui adoptent l&#039;IA, le r\u00f4le du RSSI \u00e9volue radicalement. La plupart de mes coll\u00e8gues RSSI, forts de plusieurs ann\u00e9es d&#039;exp\u00e9rience, h\u00e9sitent encore \u00e0 l&#039;utiliser, et je pense que cette h\u00e9sitation est un v\u00e9ritable handicap. L&#039;IA est l&#039;arme la plus puissante jamais con\u00e7ue en cybers\u00e9curit\u00e9. Nous travaillons \u00e0 \u00eatre capables de fournir un code exempt de vuln\u00e9rabilit\u00e9s avant m\u00eame sa mise en production. J&#039;aurais \u00e9t\u00e9 impensable il y a quelques ann\u00e9es\u00a0: la technologie n&#039;\u00e9tait tout simplement pas au point.<\/p>\n<p>Concr\u00e8tement, cela signifie que les RSSI qui adoptent l&#039;IA devront \u00eatre \u00e0 la fois des responsables de la s\u00e9curit\u00e9 et des ing\u00e9nieurs. Mi-ing\u00e9nieurs en IA, mi-d\u00e9veloppeurs. Il est essentiel de comprendre le fonctionnement et les capacit\u00e9s des outils, car on passe son temps \u00e0 cr\u00e9er des applications. Diriger une \u00e9quipe d&#039;ing\u00e9nieurs en s\u00e9curit\u00e9 qui sont aussi d\u00e9veloppeurs repr\u00e9sente l&#039;avenir de ce secteur, et je pense que nous y parvenons plus vite que pr\u00e9vu.<\/p>\n<p>Les fronti\u00e8res entre RSSI et responsable de l&#039;IA s&#039;estompent. Un RSSI qui int\u00e8gre pleinement l&#039;IA et un responsable de l&#039;IA qui prend la s\u00e9curit\u00e9 au s\u00e9rieux occupent d\u00e9sormais des r\u00f4les quasiment identiques.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"You_came_to_the_CISO_role_with_an_MBA_and_a_background_in_product_and_software_development_alongside_your_security_credentials_That_is_not_the_typical_profile_How_has_that_broader_background_shaped_your_work_and_do_you_think_the_role_demands_more_business_fluency_than_most_organizations_assume_when_they_are_hiring\"><\/span>Vous avez acc\u00e9d\u00e9 au poste de RSSI avec un MBA et une exp\u00e9rience en d\u00e9veloppement de produits et de logiciels, en plus de vos comp\u00e9tences en s\u00e9curit\u00e9. Ce profil est atypique. Comment cette formation plus diversifi\u00e9e a-t-elle influenc\u00e9 votre travail\u00a0? Pensez-vous que ce poste exige une plus grande aisance avec les enjeux commerciaux que ce que la plupart des entreprises supposent lors d&#039;un recrutement\u00a0?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La ma\u00eetrise des enjeux commerciaux est essentielle pour un RSSI efficace. Nombre de responsables de la s\u00e9curit\u00e9, m\u00eame parmi les plus comp\u00e9tents techniquement, rencontrent des difficult\u00e9s car il est indispensable de savoir dialoguer avec le conseil d&#039;administration et la direction pour mener \u00e0 bien les projets. Dans le milieu de la s\u00e9curit\u00e9, certaines d\u00e9cisions sont influenc\u00e9es par la peur, l&#039;incertitude et le doute. Si cette approche a sa place, elle a ses limites. Comprendre les besoins et les attentes de l&#039;entreprise, et adapter la s\u00e9curit\u00e9 en cons\u00e9quence, repr\u00e9sente un atout consid\u00e9rable.<\/p>\n<p>Parall\u00e8lement, il est impossible de n\u00e9gliger les aspects techniques. Sans cela, vous serez un RSSI peu efficace, car vous ne comprendrez pas r\u00e9ellement les risques que vous g\u00e9rez. \u00catre RSSI, c&#039;est jouer avec le feu en permanence. Si vous ma\u00eetrisez votre sujet, vous comprenez les impacts, vous savez ce qui pourrait mal tourner et comment r\u00e9agir. Sans cela, la situation peut d\u00e9g\u00e9n\u00e9rer. J&#039;en ai \u00e9t\u00e9 t\u00e9moin. Les deux sont indispensables \u00e0 la r\u00e9ussite.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Most_of_the_security_conversation_right_now_is_dominated_by_AI_What_I_want_to_know_is_what_forward-thinking_CISOs_should_be_doing_today_to_prepare_for_the_risk_that_quantum_computing_may_soon_pose\"><\/span>L&#039;intelligence artificielle domine actuellement les d\u00e9bats sur la s\u00e9curit\u00e9. Je souhaite savoir ce que les RSSI visionnaires devraient faire d\u00e8s aujourd&#039;hui pour se pr\u00e9parer aux risques que l&#039;informatique quantique pourrait bient\u00f4t engendrer.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Quantum est un sujet complexe, et la raison en est structurelle. Les RSSI sont, par nature, concentr\u00e9s sur l&#039;urgence imm\u00e9diate. On m&#039;a un jour d\u00e9crit leur r\u00f4le comme celui d&#039;\u00eatre parachut\u00e9 au beau milieu d&#039;un incendie de for\u00eat et charg\u00e9 d&#039;en trouver le p\u00e9rim\u00e8tre. Si quelque chose n&#039;est pas urgent et critique, la plupart d&#039;entre nous n&#039;y pr\u00eatent pas une attention particuli\u00e8re, \u00e0 moins d&#039;adopter une approche strat\u00e9gique d\u00e9lib\u00e9r\u00e9e.<\/p>\n<p>L&#039;informatique quantique entre actuellement dans cette cat\u00e9gorie. Nous savons qu&#039;elle finira par compromettre la plupart des syst\u00e8mes de chiffrement. Les normes de chiffrement compatibles avec l&#039;informatique quantique, actuellement en d\u00e9veloppement, sont th\u00e9oriquement solides, mais nous ignorons encore comment elles r\u00e9sisteront \u00e0 l&#039;\u00e9preuve du temps. La mise \u00e0 jour des syst\u00e8mes cryptographiques, le passage aux cl\u00e9s d&#039;acc\u00e8s, le renforcement de l&#039;authentification \u00e0 deux facteurs\u00a0: tout cela sera n\u00e9cessaire et repr\u00e9sente un travail r\u00e9alisable. Des experts travaillent d\u00e9j\u00e0 \u00e0 l&#039;\u00e9laboration de ces normes, et nous les adopterons tous.<\/p>\n<p>\u00c0 mon avis, les cryptomonnaies seront la premi\u00e8re cible lorsque l&#039;informatique quantique sera pleinement op\u00e9rationnelle. Le premier pays \u00e0 y parvenir s&#039;attaquera probablement au Bitcoin, et le tumulte que cela engendrera donnera aux autres le temps de mettre au point leurs syst\u00e8mes de chiffrement.<\/p>\n<p>Les conseils d&#039;administration devraient interroger leurs RSSI sur leurs intentions. Les RSSI doivent \u00eatre au fait des derni\u00e8res \u00e9volutions. Si j&#039;ai bien compris, l&#039;informatique quantique doit r\u00e9soudre environ huit probl\u00e8mes fondamentaux, dont la moiti\u00e9 sont d\u00e9j\u00e0 r\u00e9solus. Nous avons du temps devant nous. Par ailleurs, la gestion de cette p\u00e9riode d&#039;intelligence artificielle pr\u00e9sente un avantage ind\u00e9niable\u00a0: la rapidit\u00e9 et l&#039;adaptabilit\u00e9 qu&#039;elle impose aux \u00e9quipes de s\u00e9curit\u00e9 constituent pr\u00e9cis\u00e9ment la pr\u00e9paration n\u00e9cessaire. Un RSSI qui survivra \u00e0 cette p\u00e9riode sera bien positionn\u00e9 lorsque l&#039;informatique quantique atteindra son apog\u00e9e.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"The_boundary_between_security_and_product_engineering_seems_to_be_shifting_How_do_you_think_about_where_securitys_responsibility_ends_and_engineerings_begins\"><\/span>La fronti\u00e8re entre la s\u00e9curit\u00e9 et l&#039;ing\u00e9nierie produit semble \u00e9voluer. Comment d\u00e9finissez-vous o\u00f9 s&#039;arr\u00eate la responsabilit\u00e9 de la s\u00e9curit\u00e9 et o\u00f9 commence celle de l&#039;ing\u00e9nierie\u00a0?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Ce sont les deux faces d&#039;une m\u00eame pi\u00e8ce, et cela ne changera pas. L&#039;ing\u00e9nierie produit vise \u00e0 optimiser le fonctionnement des produits et \u00e0 am\u00e9liorer l&#039;exp\u00e9rience utilisateur. La s\u00e9curit\u00e9, quant \u00e0 elle, s&#039;attache \u00e0 analyser en profondeur la conception des syst\u00e8mes et \u00e0 d\u00e9celer les failles que les ing\u00e9nieurs fonctionnels n\u00e9gligent. Ces deux perspectives sont indispensables et aucune n&#039;est sup\u00e9rieure \u00e0 l&#039;autre\u00a0; elles sont simplement diff\u00e9rentes.<\/p>\n<p>En d\u00e9but de carri\u00e8re, un RSSI doit g\u00e9rer ces tensions avec une grande difficult\u00e9. Il est rarement bienvenu que les \u00e9quipes de s\u00e9curit\u00e9 viennent reprocher aux ing\u00e9nieurs leurs erreurs, et le conflit sous-jacent porte g\u00e9n\u00e9ralement sur le temps et les ressources. Apprendre \u00e0 repenser cette relation, \u00e0 se positionner comme un partenaire plut\u00f4t que comme un auditeur, est l&#039;un des d\u00e9fis les plus complexes pour un RSSI. Il m&#039;a fallu des ann\u00e9es pour y parvenir.<\/p>\n<p>Ce qui a acc\u00e9l\u00e9r\u00e9 cette transformation, au-del\u00e0 de l&#039;exp\u00e9rience, c&#039;est l&#039;IA. Des t\u00e2ches qui n\u00e9cessitaient des semaines de travail d&#039;ing\u00e9nierie peuvent d\u00e9sormais \u00eatre r\u00e9alis\u00e9es en quelques minutes. Lorsque la s\u00e9curit\u00e9 cesse d&#039;\u00eatre un frein, le dialogue avec les \u00e9quipes produit change radicalement et les barri\u00e8res qui d\u00e9finissaient cette relation s&#039;estompent d&#039;elles-m\u00eames.<\/p>\n<p>La confiance est essentielle pour y parvenir. Comprendre les motivations des \u00e9quipes produit, leurs points de r\u00e9sistance, et devenir leur partenaire plut\u00f4t qu&#039;un adversaire, voil\u00e0 comment instaurer la confiance et, par cons\u00e9quent, mener \u00e0 bien les projets. Simple en th\u00e9orie, mais complexe en pratique.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"If_you_were_sitting_in_a_room_full_of_CEOs_and_board_members_about_to_conduct_a_CISO_search_what_should_be_on_their_radar_that_might_not_be\"><\/span>Si vous \u00e9tiez assis dans une salle remplie de PDG et de membres de conseils d&#039;administration sur le point de lancer une recherche de RSSI, quels \u00e9l\u00e9ments devraient retenir leur attention et qui pourraient ne pas l&#039;\u00eatre ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La cr\u00e9ativit\u00e9 et la capacit\u00e9 d&#039;adaptation. Ce sont les qualit\u00e9s les plus souvent n\u00e9glig\u00e9es.<\/p>\n<p>Les risques que les RSSI devront g\u00e9rer cette ann\u00e9e sont des risques que nous commen\u00e7ons \u00e0 peine \u00e0 appr\u00e9hender. Il y a un an, l&#039;IA agentielle et son potentiel au sein d&#039;un environnement d&#039;entreprise, une fois connect\u00e9e \u00e0 l&#039;ensemble des syst\u00e8mes via un serveur MCP par exemple, ne repr\u00e9sentaient pas une pr\u00e9occupation majeure pour la plupart des \u00e9quipes de s\u00e9curit\u00e9. Il y a six mois, ce sujet \u00e9tait quasiment ignor\u00e9. L&#039;apparition de nouvelles menaces est fulgurante, et le RSSI de demain devra \u00eatre capable d&#039;apprendre rapidement une nouvelle technologie, de la tester, d&#039;en d\u00e9finir les mesures de s\u00e9curit\u00e9, puis de les mettre en \u0153uvre sans freiner l&#039;innovation que l&#039;entreprise s&#039;efforce de d\u00e9velopper.<\/p>\n<p>Cela exige une r\u00e9elle cr\u00e9ativit\u00e9. Le plus int\u00e9ressant, c&#039;est que le parcours traditionnel en s\u00e9curit\u00e9 informatique \u2013 hacking, tests d&#039;intrusion, \u00e9quipes rouges \u2013 d\u00e9veloppe pr\u00e9cis\u00e9ment ce type de raisonnement. On analyse un probl\u00e8me et on trouve des solutions inattendues. Cet instinct est directement transposable. Les RSSI issus de ces formations constituent toujours un vivier important.<\/p>\n<p>Mais les conseils d&#039;administration doivent rechercher explicitement ces qualit\u00e9s cr\u00e9atives et d&#039;adaptation, et ne pas se contenter de v\u00e9rifier les comp\u00e9tences techniques ou l&#039;exp\u00e9rience. L&#039;expertise technique est importante, certes, mais elle constitue un pr\u00e9requis. Ce qui distinguera les RSSI qui r\u00e9ussissent de ceux qui \u00e9chouent, c&#039;est leur capacit\u00e9 \u00e0 \u00e9voluer dans des conditions diff\u00e9rentes de celles qui existaient \u00e0 leur prise de fonction.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>Entretien avec Joshua Foltz, ancien CISO chez NerdWallet<\/p>","protected":false},"author":1,"featured_media":145027,"template":"","interview-categories":[11362],"class_list":["post-145026","interviews","type-interviews","status-publish","has-post-thumbnail","hentry","interview-categories-cybersecurity"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Joshua Foltz, Former NerdWallet CISO, on security leadership<\/title>\n<meta name=\"description\" content=\"Former NerdWallet CISO Joshua Foltz on why creativity matters more than credentials in CISO hiring, how AI is transforming security, and what boards miss.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.n2growth.com\/fr\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joshua Foltz, Former NerdWallet CISO, on security leadership\" \/>\n<meta property=\"og:description\" content=\"Former NerdWallet CISO Joshua Foltz on why creativity matters more than credentials in CISO hiring, how AI is transforming security, and what boards miss.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.n2growth.com\/fr\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/\" \/>\n<meta property=\"og:site_name\" content=\"N2Growth\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/n2growth\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T14:10:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1084\" \/>\n\t<meta property=\"og:image:height\" content=\"1003\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Joshua Foltz, Former NerdWallet CISO, on security leadership\" \/>\n<meta name=\"twitter:description\" content=\"Former NerdWallet CISO Joshua Foltz on why creativity matters more than credentials in CISO hiring, how AI is transforming security, and what boards miss.\" \/>\n<meta name=\"twitter:site\" content=\"@n2growth\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Joshua Foltz, ancien RSSI de NerdWallet, sur le leadership en mati\u00e8re de s\u00e9curit\u00e9","description":"Joshua Foltz, ancien RSSI de NerdWallet, explique pourquoi la cr\u00e9ativit\u00e9 compte plus que les dipl\u00f4mes lors du recrutement d&#039;un RSSI, comment l&#039;IA transforme la s\u00e9curit\u00e9 et ce que les conseils d&#039;administration n\u00e9gligent.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.n2growth.com\/fr\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/","og_locale":"fr_FR","og_type":"article","og_title":"Joshua Foltz, Former NerdWallet CISO, on security leadership","og_description":"Former NerdWallet CISO Joshua Foltz on why creativity matters more than credentials in CISO hiring, how AI is transforming security, and what boards miss.","og_url":"https:\/\/www.n2growth.com\/fr\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/","og_site_name":"N2Growth","article_publisher":"https:\/\/www.facebook.com\/n2growth","article_modified_time":"2026-07-15T14:10:16+00:00","og_image":[{"width":1084,"height":1003,"url":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Joshua Foltz, Former NerdWallet CISO, on security leadership","twitter_description":"Former NerdWallet CISO Joshua Foltz on why creativity matters more than credentials in CISO hiring, how AI is transforming security, and what boards miss.","twitter_site":"@n2growth","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.n2growth.com\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/","url":"https:\/\/www.n2growth.com\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/","name":"Joshua Foltz, ancien RSSI de NerdWallet, sur le leadership en mati\u00e8re de s\u00e9curit\u00e9","isPartOf":{"@id":"https:\/\/www.n2growth.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.n2growth.com\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/#primaryimage"},"image":{"@id":"https:\/\/www.n2growth.com\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/#primaryimage"},"thumbnailUrl":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz.jpg","datePublished":"2026-06-24T15:19:29+00:00","dateModified":"2026-07-15T14:10:16+00:00","description":"Joshua Foltz, ancien RSSI de NerdWallet, explique pourquoi la cr\u00e9ativit\u00e9 compte plus que les dipl\u00f4mes lors du recrutement d&#039;un RSSI, comment l&#039;IA transforme la s\u00e9curit\u00e9 et ce que les conseils d&#039;administration n\u00e9gligent.","breadcrumb":{"@id":"https:\/\/www.n2growth.com\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.n2growth.com\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.n2growth.com\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/#primaryimage","url":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz.jpg","contentUrl":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/06\/Joshua-Foltz.jpg","width":1084,"height":1003,"caption":"A conversation with Joshua Foltz, former CISO at NerdWallet"},{"@type":"BreadcrumbList","@id":"https:\/\/www.n2growth.com\/interviews\/joshua-foltz-former-ciso-at-nerdwallet-on-what-it-takes-to-lead-security-today\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.n2growth.com\/"},{"@type":"ListItem","position":2,"name":"Joshua Foltz, former CISO at NerdWallet, on what it takes to lead security today"}]},{"@type":"WebSite","@id":"https:\/\/www.n2growth.com\/#website","url":"https:\/\/www.n2growth.com\/","name":"N2Growth","description":"Nous trouvons et d\u00e9veloppons les meilleurs leaders du monde","publisher":{"@id":"https:\/\/www.n2growth.com\/#organization"},"alternateName":"N2 Growth","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.n2growth.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.n2growth.com\/#organization","name":"N2Growth","alternateName":"N2 Growth","url":"https:\/\/www.n2growth.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.n2growth.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2019\/05\/N2Growth-Logo-Dark.png","contentUrl":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2019\/05\/N2Growth-Logo-Dark.png","width":500,"height":142,"caption":"N2Growth"},"image":{"@id":"https:\/\/www.n2growth.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/n2growth","https:\/\/x.com\/n2growth","https:\/\/www.instagram.com\/n2growth","https:\/\/www.linkedin.com\/company\/n2growth","https:\/\/www.pinterest.com\/gon2growth\/","https:\/\/www.youtube.com\/c\/n2growth-"],"description":"Cabinet international de recrutement de cadres, de coaching ex\u00e9cutif et de conseil en leadership","email":"press@n2growth.com","telephone":"+18009444662","legalName":"N2Growth Inc.","foundingDate":"2006-05-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}}]}},"_links":{"self":[{"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/interviews\/145026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/interviews"}],"about":[{"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/types\/interviews"}],"author":[{"embeddable":true,"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/media\/145027"}],"wp:attachment":[{"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/media?parent=145026"}],"wp:term":[{"taxonomy":"interview-categories","embeddable":true,"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/interview-categories?post=145026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}