{"id":146772,"date":"2026-08-20T05:09:32","date_gmt":"2026-08-20T09:09:32","guid":{"rendered":"https:\/\/www.n2growth.com\/?post_type=interviews&#038;p=146772"},"modified":"2026-08-19T23:48:05","modified_gmt":"2026-08-20T03:48:05","slug":"madhuri-andrews-on-people-first-technology-leadership","status":"publish","type":"interviews","link":"https:\/\/www.n2growth.com\/fr\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/","title":{"rendered":"Madhuri Andrews sur le leadership technologique ax\u00e9 sur les personnes"},"content":{"rendered":"<section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><img decoding=\"async\" class=\"alignleft wp-image-146771 size-medium\" src=\"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews-300x278.jpg\" alt=\"Une conversation avec Madhuri Andrews, vice-pr\u00e9sidente ex\u00e9cutive et directrice des syst\u00e8mes d&#039;information chez MKS Inc., et membre du conseil d&#039;administration d&#039;Applied Industrial Technologies, Inc.\" width=\"300\" height=\"278\" srcset=\"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews-300x278.jpg 300w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews-1024x947.jpg 1024w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews-13x12.jpg 13w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews-150x139.jpg 150w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews.jpg 1084w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">\u00c0 l&#039;heure o\u00f9 la technologie \u00e9volue plus vite que la plupart des organisations ne peuvent l&#039;int\u00e9grer, le leadership technologique est plus crucial que jamais. Madhuri nous rappelle que le leadership centr\u00e9 sur l&#039;humain demeure la cl\u00e9 de l&#039;efficacit\u00e9 des DSI, explique comment cela se traduit concr\u00e8tement, partage son point de vue sur les crit\u00e8res de recrutement d&#039;un DSI pour les conseils d&#039;administration et s&#039;appuie sur son exp\u00e9rience de DSI et d&#039;administratrice pour d\u00e9finir les conditions n\u00e9cessaires \u00e0 la r\u00e9ussite d&#039;un DSI.<\/span><\/p>\n<p><a href=\"https:\/\/www.linkedin.com\/in\/madhuri-andrews\/\"><span style=\"font-weight: 400;\">Madhuri Andrews<\/span><\/a><span style=\"font-weight: 400;\"> est vice-pr\u00e9sident ex\u00e9cutif et directeur des syst\u00e8mes d&#039;information chez <\/span><a href=\"https:\/\/www.mks.com\/\"><span style=\"font-weight: 400;\">MKS<\/span><\/a><span style=\"font-weight: 400;\">, Elle dirige la strat\u00e9gie technologique de l&#039;entreprise, favorisant ainsi sa croissance et l&#039;excellence op\u00e9rationnelle \u00e0 l&#039;\u00e9chelle mondiale. Forte d&#039;une exp\u00e9rience en direction des technologies et des affaires dans les secteurs de l&#039;a\u00e9rospatiale et de la d\u00e9fense, de l&#039;industrie, des hautes technologies, des infrastructures et des services professionnels, elle si\u00e8ge \u00e9galement au conseil d&#039;administration d&#039;Applied Industrial Technologies, Inc. (AIT). Elle a \u00e9t\u00e9 reconnue parmi les 100 meilleurs DSI au monde, intronis\u00e9e au Temple de la renomm\u00e9e des DSI, laur\u00e9ate du prix BostonCIO ORBIE Global Award et nomm\u00e9e parmi les 100 personnalit\u00e9s am\u00e9ricaines d&#039;origine asiatique les plus influentes, entre autres distinctions professionnelles.<\/span><\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2><span class=\"ez-toc-section\" id=\"To_start_we_all_know_technology_is_changing_at_a_remarkable_pace_right_now_but_I_want_to_be_a_bit_counterintuitive_and_ask_about_the_other_side_of_that_story_What_do_you_think_are_the_keys_to_success_as_a_CIO_that_remain_constant_no_matter_what_is_changing_in_the_technology_landscape_or_what_industry_you_are_serving_in\"><\/span>Pour commencer, nous savons tous que la technologie \u00e9volue \u00e0 un rythme remarquable actuellement, mais j&#039;aimerais aborder un aspect moins conventionnel de la question. Selon vous, quels sont les facteurs cl\u00e9s de succ\u00e8s d&#039;un DSI qui demeurent constants, quelles que soient les \u00e9volutions du paysage technologique ou le secteur d&#039;activit\u00e9\u00a0?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>C&#039;est un d\u00e9fi l\u00e9gitime, car le rythme du changement est au c\u0153ur des discussions. Mais lorsque j&#039;analyse les facteurs de r\u00e9ussite des DSI aujourd&#039;hui, quatre \u00e9l\u00e9ments reviennent constamment, et aucun n&#039;est nouveau.<\/p>\n<p>L&#039;impact sur l&#039;activit\u00e9 est primordial et constant. Pour moi, la technologie est g\u00e9n\u00e9ralement un moyen d&#039;atteindre un objectif, et non une fin en soi. La question est toujours la m\u00eame\u00a0: comment aider l&#039;organisation \u00e0 se d\u00e9velopper, \u00e0 fonctionner plus efficacement, \u00e0 mieux servir ses clients et \u00e0 g\u00e9rer les risques plus intelligemment\u00a0? Cette orientation reste inchang\u00e9e malgr\u00e9 l&#039;\u00e9volution technologique.<\/p>\n<p>La confiance est un \u00e9l\u00e9ment essentiel. Les organisations ont besoin de dirigeants capables de g\u00e9rer la complexit\u00e9, de prendre des d\u00e9cisions judicieuses et de faire preuve de transparence quant aux compromis \u00e0 faire. Et pour cela, pour obtenir la cr\u00e9dibilit\u00e9 indispensable, la confiance est indispensable. Cela a toujours \u00e9t\u00e9 vrai et je ne vois pas cela changer.<\/p>\n<p>Il y a ensuite la discipline d&#039;ex\u00e9cution, souvent n\u00e9glig\u00e9e \u00e0 mon avis. On peut avoir la meilleure strat\u00e9gie et la meilleure vision, mais si l&#039;on est incapable d&#039;agir de mani\u00e8re constante et de cr\u00e9er une r\u00e9elle valeur ajout\u00e9e, cela n&#039;a aucune importance. Cela vaut pour tous les domaines\u00a0: op\u00e9rations, cybers\u00e9curit\u00e9, intelligence artificielle g\u00e9n\u00e9rative ou mise en \u0153uvre d&#039;initiatives commerciales.<\/p>\n<p>Et ce qui me tient le plus \u00e0 c\u0153ur, c&#039;est le leadership humain. Peu importe les avanc\u00e9es technologiques\u00a0: ce sont les personnes qui, au final, font la diff\u00e9rence. Constituer des \u00e9quipes performantes, d\u00e9velopper les talents, accompagner le changement\u00a0: autant d&#039;\u00e9l\u00e9ments qui ont toujours \u00e9t\u00e9 essentiels \u00e0 ce r\u00f4le. La technologie \u00e9volue, certes, mais les fondamentaux du leadership, eux, restent les m\u00eames.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"You_describe_yourself_as_a_people-first_leader_and_have_said_that_people_are_the_heart_of_every_organization_That_is_maybe_something_of_an_unusual_posture_for_someone_in_a_role_so_often_reduced_to_systems_and_infrastructure_But_what_I_want_to_know_is_in_practical_terms_how_do_you_operate_as_a_people-first_CIO_What_do_you_do\"><\/span>Vous vous d\u00e9crivez comme un leader qui place l&#039;humain au c\u0153ur de ses priorit\u00e9s et affirmez que les individus sont le c\u0153ur de toute organisation. Cette position est peut-\u00eatre quelque peu inhabituelle pour quelqu&#039;un dont le r\u00f4le est si souvent r\u00e9duit aux syst\u00e8mes et \u00e0 l&#039;infrastructure. Mais ce que je souhaite savoir, c&#039;est concr\u00e8tement comment vous mettez en pratique le r\u00f4le d&#039;un DSI qui place l&#039;humain au centre de ses pr\u00e9occupations\u00a0? Quelles sont vos actions\u00a0?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Pour moi, \u00ab\u00a0l\u2019humain d\u2019abord\u00a0\u00bb n\u2019est ni un slogan ni une philosophie. C\u2019est un principe de fonctionnement. C\u2019est une question de comportement au quotidien.<\/p>\n<p>Et tout commence, syst\u00e9matiquement, par l&#039;\u00e9coute. Non pas pour r\u00e9pondre, mais pour comprendre, et ensuite pour aider. Il est essentiel de savoir o\u00f9 en sont vos \u00e9quipes, o\u00f9 elles rencontrent des difficult\u00e9s, o\u00f9 se situent les points de friction, quelles priorit\u00e9s sont n\u00e9glig\u00e9es. On ne peut y parvenir par supposition. C&#039;est le fondement m\u00eame de tout.<\/p>\n<p>\u00c0 partir de l\u00e0, il s&#039;agit de cr\u00e9er un environnement propice. Je sais que cela peut para\u00eetre clich\u00e9, mais pour moi, c&#039;est tr\u00e8s pr\u00e9cis. Il s&#039;agit de d\u00e9finir clairement les objectifs de chacun, de leur donner les moyens d&#039;y parvenir et de les responsabiliser. Quand les gens connaissent leurs responsabilit\u00e9s et se sentent en confiance, la qualit\u00e9 de leur travail s&#039;en trouve am\u00e9lior\u00e9e. On le ressent. Tout le monde le ressent.<\/p>\n<p>Le d\u00e9veloppement des talents est une priorit\u00e9 pour les dirigeants et un pilier d&#039;un leadership centr\u00e9 sur l&#039;humain. Si les recrutements externes apportent de nouvelles comp\u00e9tences et perspectives, les employ\u00e9s actuels offrent une connaissance approfondie de l&#039;entreprise, un contexte pr\u00e9cis et une exp\u00e9rience institutionnelle inestimables, difficilement rempla\u00e7ables. Les organisations les plus performantes savent trouver un \u00e9quilibre entre ces deux aspects\u00a0: investir dans le d\u00e9veloppement des talents internes tout en int\u00e9grant strat\u00e9giquement des experts externes. En d\u00e9veloppant les comp\u00e9tences de leurs employ\u00e9s actuels et en facilitant l&#039;int\u00e9gration et la contribution des nouvelles recrues, les organisations b\u00e2tissent des \u00e9quipes plus performantes et un vivier de talents plus durable.<\/p>\n<p>Et puis il y a la dimension humaine, qui, \u00e0 mon avis, est souvent n\u00e9glig\u00e9e dans les discussions sur le leadership technologique. Lorsqu&#039;on int\u00e8gre une organisation et qu&#039;il faut innover \u2013 ce qui est presque toujours le cas dans ce contexte \u2013, on peut n\u00e9anmoins le faire avec empathie et transparence, en aidant chacun \u00e0 comprendre les raisons de ces changements. Car, au final, les individus donnent le meilleur d&#039;eux-m\u00eames lorsqu&#039;ils se sentent respect\u00e9s, soutenus et en phase avec la mission. Nous savons tous ce que cela signifie, et nous savons tous quand cela fait d\u00e9faut.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Given_everything_that_is_happening_right_now_with_AI_agentic_systems_and_the_pace_of_change_more_broadly_what_are_you_doing_differently_as_a_leader_today_than_you_were_five_years_ago\"><\/span>Compte tenu de tout ce qui se passe actuellement avec l&#039;IA, les syst\u00e8mes multi-agents et le rythme des changements en g\u00e9n\u00e9ral, qu&#039;est-ce que vous faites diff\u00e9remment en tant que leader aujourd&#039;hui par rapport \u00e0 il y a cinq ans ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Ce qui change le plus, \u00e0 mon sens, c&#039;est l&#039;importance accord\u00e9e \u00e0 l&#039;adaptabilit\u00e9 et \u00e0 la rapidit\u00e9 d&#039;apprentissage, et ce, \u00e0 tous les niveaux. Il n&#039;y a pas si longtemps, l&#039;accent \u00e9tait davantage mis sur la disponibilit\u00e9 d&#039;une infrastructure technologique ad\u00e9quate et sur la capacit\u00e9 \u00e0 mettre en \u0153uvre un plan. Cela se justifiait dans un contexte plus stable. Aujourd&#039;hui, ce qui compte le plus, c&#039;est la curiosit\u00e9 des dirigeants, leur volont\u00e9 d&#039;apprendre et leur capacit\u00e9 d&#039;adaptation, car plus rien n&#039;est fig\u00e9. L&#039;id\u00e9e qu&#039;il suffisait de concevoir une architecture technologique et de s&#039;y tenir a compl\u00e8tement disparu.<\/p>\n<p>Il y a actuellement beaucoup de bruit dans le secteur, ce qui repr\u00e9sente un v\u00e9ritable d\u00e9fi pour le leadership. D\u00e9m\u00ealer le vrai du faux\u00a0? Pour y voir clair, il faut se concentrer. Il est essentiel de savoir o\u00f9 approfondir et o\u00f9 cela ne l&#039;est pas, et de structurer l&#039;exp\u00e9rimentation. Tester, mettre \u00e0 l&#039;\u00e9chelle et apprendre sont certes cruciaux, mais seulement s&#039;ils sont encadr\u00e9s par un cadre coh\u00e9rent. Il faut un espace propice \u00e0 l&#039;innovation sans pour autant perdre la rigueur n\u00e9cessaire \u00e0 sa mise en \u0153uvre.<\/p>\n<p>Le changement que j&#039;appr\u00e9cie particuli\u00e8rement, c&#039;est la prise de conscience accrue de l&#039;importance de la qualit\u00e9 et de la gouvernance des donn\u00e9es. Auparavant, ces discussions \u00e9taient per\u00e7ues tout autrement. Aborder le sujet de la gouvernance des donn\u00e9es laissait les gens perplexes. D\u00e9sormais, lorsqu&#039;on en parle, on comprend imm\u00e9diatement son importance, et c&#039;est une cons\u00e9quence directe de l&#039;essor de l&#039;IA. Car voici le point essentiel, et je vais \u00eatre franc\u00a0: sans donn\u00e9es de qualit\u00e9, l&#039;IA ne vous apportera rien de concret. Seules les organisations qui investissent dans la qualit\u00e9 des donn\u00e9es peuvent exploiter pleinement ces capacit\u00e9s. Si les donn\u00e9es d&#039;entr\u00e9e sont erron\u00e9es, les r\u00e9sultats le seront aussi, et aucun outil, aussi sophistiqu\u00e9 soit-il, ne changera cette \u00e9quation.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Boards_are_appointing_more_CIOs_with_CS_degrees_and_deep_technical_backgrounds_and_fewer_with_traditional_MBA_profiles_Is_that_the_right_move_or_are_boards_potentially_making_a_mistake\"><\/span>Les conseils d&#039;administration nomment davantage de DSI titulaires d&#039;un dipl\u00f4me en informatique et poss\u00e9dant une solide exp\u00e9rience technique, et moins de profils issus du MBA traditionnel. Est-ce un choix judicieux, ou les conseils d&#039;administration commettent-ils une erreur\u00a0?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>J&#039;y ai beaucoup r\u00e9fl\u00e9chi, notamment en m&#039;appuyant sur ma propre exp\u00e9rience au sein de conseils d&#039;administration d&#039;entreprises publiques et priv\u00e9es. Et pour moi, ce n&#039;est pas vraiment un choix.<\/p>\n<p>Oui, un DSI doit poss\u00e9der une expertise technique pointue. Il doit ma\u00eetriser la cybers\u00e9curit\u00e9, l&#039;architecture des donn\u00e9es, la strat\u00e9gie de plateforme et anticiper l&#039;\u00e9volution des technologies \u00e9mergentes. Ce sont des pr\u00e9requis indispensables. Mais la seule ma\u00eetrise technique ne suffit pas \u00e0 garantir \u00e0 un DSI une place au sein de la direction ou du conseil d&#039;administration. Il faut aussi \u00eatre un leader d&#039;entreprise. Il faut parler le langage des affaires et \u00eatre capable de traduire, de faire le lien entre ses actions techniques et leurs implications pour l&#039;organisation.<\/p>\n<p>Le mod\u00e8le auquel je reviens sans cesse est celui du leader en T. La dimension verticale correspond \u00e0 votre expertise technique, et bien s\u00fbr, le DSI doit poss\u00e9der une solide expertise dans ce domaine. Mais pour un DSI, la dimension horizontale, c&#039;est-\u00e0-dire la capacit\u00e9 \u00e0 collaborer avec l&#039;ensemble de l&#039;organisation et \u00e0 relier la technologie \u00e0 la valeur ajout\u00e9e pour l&#039;entreprise, repr\u00e9sente la part la plus importante et la plus exigeante de son r\u00f4le. Si vous ne ma\u00eetrisez que la dimension verticale, vous aurez du mal \u00e0 \u00eatre aussi efficace que ce poste l&#039;exige. Vous devez \u00eatre bilingue\u00a0: technique et commercial. Et si vous ne poss\u00e9dez pas les deux, je pense qu&#039;il vous sera tr\u00e8s difficile d&#039;avoir l&#039;impact attendu.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"If_you_were_sitting_in_front_of_a_room_full_of_CEOs_and_board_members_what_would_you_tell_them_about_how_to_set_a_CIO_up_to_succeed_once_they_have_been_chosen\"><\/span>Si vous \u00e9tiez assis devant une salle remplie de PDG et de membres de conseils d&#039;administration, que leur diriez-vous sur la fa\u00e7on de pr\u00e9parer un DSI \u00e0 r\u00e9ussir une fois qu&#039;il aura \u00e9t\u00e9 choisi ?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Nombre de DSI prennent leurs fonctions avec un mandat trop vague ou trop vaste pour \u00eatre op\u00e9rationnel. Les organisations qui r\u00e9ussissent \u00e0 g\u00e9rer cette situation l&#039;ont d\u00e9j\u00e0 anticip\u00e9e lors du processus de s\u00e9lection, avant m\u00eame de faire une offre. Soyez clair sur les raisons de ce recrutement. S&#039;agit-il de stabiliser les op\u00e9rations\u00a0? De mener une transformation\u00a0? De moderniser le c\u0153ur de m\u00e9tier\u00a0? De favoriser l&#039;adoption de l&#039;IA\u00a0? De renforcer la cybers\u00e9curit\u00e9\u00a0? Les DSI h\u00e9ritent presque toujours d&#039;un programme ambitieux, et c&#039;est normal, mais si la r\u00e9ussite n&#039;est pas clairement d\u00e9finie d\u00e8s le premier jour, vous compliquez inutilement la t\u00e2che. Et si vous n&#039;\u00eates pas certain du mandat, soyez transparent. Les meilleurs DSI que je connaisse pr\u00e9f\u00e8rent mener leur propre \u00e9valuation plut\u00f4t que de se voir imposer des priorit\u00e9s qui s&#039;av\u00e8rent d\u00e9connect\u00e9es de la r\u00e9alit\u00e9.<\/p>\n<p>Au-del\u00e0 du mandat, il est essentiel de bien r\u00e9fl\u00e9chir \u00e0 la mani\u00e8re dont vous consid\u00e9rez le DSI\u00a0: comme un partenaire strat\u00e9gique au sein de la direction ou comme un simple ex\u00e9cutant. Ces deux relations sont radicalement diff\u00e9rentes. Impliquer le DSI d\u00e8s le d\u00e9but, lors des r\u00e9flexions sur les fusions-acquisitions, des d\u00e9cisions relatives au mod\u00e8le op\u00e9rationnel ou de l&#039;\u00e9laboration de la strat\u00e9gie, est totalement diff\u00e9rent de lui confier des t\u00e2ches \u00e0 accomplir apr\u00e8s coup. Si vous souhaitez qu&#039;il contribue \u00e0 fa\u00e7onner les r\u00e9sultats, il est indispensable qu&#039;il soit associ\u00e9 \u00e0 la discussion avant m\u00eame que les d\u00e9cisions ne soient prises.<\/p>\n<p>Il y a aussi la question de l&#039;autorit\u00e9, et je pense qu&#039;elle est souvent sous-estim\u00e9e. Si vous voulez que le DSI am\u00e9liore la qualit\u00e9 des donn\u00e9es, modernise les plateformes et favorise l&#039;adoption de l&#039;IA dans toute l&#039;entreprise, vous devez lui donner les moyens d&#039;agir. Un DSI n&#039;op\u00e8re pas en vase clos. Son r\u00f4le est transversal et, \u00e0 bien des \u00e9gards, il est le lien essentiel au sein de l&#039;organisation, celui qui a une vision d&#039;ensemble. Pour \u00eatre efficace, il doit pouvoir impulser le changement dans toutes les fonctions, et pas seulement au sein de la direction informatique.<\/p>\n<p>Si je devais conclure cette r\u00e9union par une seule nuance, ce serait que la technologie ne repr\u00e9sente qu&#039;environ 20 % du travail d&#039;un DSI. Les 80 % restants consistent en un leadership strat\u00e9gique, la conduite du changement transversal, l&#039;obtention de l&#039;adh\u00e9sion des \u00e9quipes et la collaboration avec les diff\u00e9rents services de l&#039;entreprise afin de garantir l&#039;impact des actions entreprises. La technologie est mise en \u0153uvre, certes, mais le travail humain est bien plus complexe. Les conseils d&#039;administration et les PDG qui l&#039;ont compris donneront \u00e0 leurs DSI les moyens de r\u00e9ussir. Ceux qui consid\u00e8rent ce poste comme une simple fonction technique s&#039;interrogeront sans cesse sur l&#039;absence de r\u00e9sultats \u00e0 la hauteur de leurs attentes.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>Une conversation avec Madhuri Andrews, vice-pr\u00e9sidente ex\u00e9cutive et directrice des syst\u00e8mes d&#039;information chez MKS Inc., et membre du conseil d&#039;administration d&#039;Applied Industrial Technologies, Inc.<\/p>","protected":false},"author":1,"featured_media":146771,"template":"","interview-categories":[11365],"class_list":["post-146772","interviews","type-interviews","status-publish","has-post-thumbnail","hentry","interview-categories-technology-and-digital"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>People First Technology Leadership and CIO Success | N2Growth<\/title>\n<meta name=\"description\" content=\"Discover insights on people first technology leadership as Madhuri Andrews shares her CIO experiences and best practices.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.n2growth.com\/fr\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Madhuri Andrews on people-first technology leadership\" \/>\n<meta property=\"og:description\" content=\"Discover insights on people first technology leadership as Madhuri Andrews shares her CIO experiences and best practices.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.n2growth.com\/fr\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/\" \/>\n<meta property=\"og:site_name\" content=\"N2Growth\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/n2growth\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1084\" \/>\n\t<meta property=\"og:image:height\" content=\"1003\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@n2growth\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Leadership technologique ax\u00e9 sur l&#039;humain et r\u00e9ussite des DSI | N2Growth","description":"D\u00e9couvrez les points de vue de Madhuri Andrews sur le leadership technologique ax\u00e9 sur l&#039;humain, en partageant son exp\u00e9rience de DSI et ses meilleures pratiques.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.n2growth.com\/fr\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/","og_locale":"fr_FR","og_type":"article","og_title":"Madhuri Andrews on people-first technology leadership","og_description":"Discover insights on people first technology leadership as Madhuri Andrews shares her CIO experiences and best practices.","og_url":"https:\/\/www.n2growth.com\/fr\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/","og_site_name":"N2Growth","article_publisher":"https:\/\/www.facebook.com\/n2growth","og_image":[{"width":1084,"height":1003,"url":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@n2growth","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.n2growth.com\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/","url":"https:\/\/www.n2growth.com\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/","name":"Leadership technologique ax\u00e9 sur l&#039;humain et r\u00e9ussite des DSI | N2Growth","isPartOf":{"@id":"https:\/\/www.n2growth.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.n2growth.com\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/#primaryimage"},"image":{"@id":"https:\/\/www.n2growth.com\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/#primaryimage"},"thumbnailUrl":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews.jpg","datePublished":"2026-08-20T09:09:32+00:00","description":"D\u00e9couvrez les points de vue de Madhuri Andrews sur le leadership technologique ax\u00e9 sur l&#039;humain, en partageant son exp\u00e9rience de DSI et ses meilleures pratiques.","breadcrumb":{"@id":"https:\/\/www.n2growth.com\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.n2growth.com\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.n2growth.com\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/#primaryimage","url":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews.jpg","contentUrl":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2026\/08\/Madhuri-Andrews.jpg","width":1084,"height":1003,"caption":"A conversation with Madhuri Andrews, EVP and CIO at MKS Inc., and Board Director, Applied Industrial Technologies, Inc."},{"@type":"BreadcrumbList","@id":"https:\/\/www.n2growth.com\/interviews\/madhuri-andrews-on-people-first-technology-leadership\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.n2growth.com\/"},{"@type":"ListItem","position":2,"name":"Madhuri Andrews on people-first technology leadership"}]},{"@type":"WebSite","@id":"https:\/\/www.n2growth.com\/#website","url":"https:\/\/www.n2growth.com\/","name":"N2Growth","description":"Nous trouvons et d\u00e9veloppons les meilleurs leaders du monde","publisher":{"@id":"https:\/\/www.n2growth.com\/#organization"},"alternateName":"N2 Growth","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.n2growth.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.n2growth.com\/#organization","name":"N2Growth","alternateName":"N2 Growth","url":"https:\/\/www.n2growth.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.n2growth.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2019\/05\/N2Growth-Logo-Dark.png","contentUrl":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2019\/05\/N2Growth-Logo-Dark.png","width":500,"height":142,"caption":"N2Growth"},"image":{"@id":"https:\/\/www.n2growth.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/n2growth","https:\/\/x.com\/n2growth","https:\/\/www.instagram.com\/n2growth","https:\/\/www.linkedin.com\/company\/n2growth","https:\/\/www.pinterest.com\/gon2growth\/","https:\/\/www.youtube.com\/c\/n2growth-"],"description":"Cabinet international de recrutement de cadres, de coaching ex\u00e9cutif et de conseil en leadership","email":"press@n2growth.com","telephone":"+18009444662","legalName":"N2Growth Inc.","foundingDate":"2006-05-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}}]}},"_links":{"self":[{"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/interviews\/146772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/interviews"}],"about":[{"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/types\/interviews"}],"author":[{"embeddable":true,"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/media\/146771"}],"wp:attachment":[{"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/media?parent=146772"}],"wp:term":[{"taxonomy":"interview-categories","embeddable":true,"href":"https:\/\/www.n2growth.com\/fr\/wp-json\/wp\/v2\/interview-categories?post=146772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}