{"id":142385,"date":"2025-12-04T05:15:00","date_gmt":"2025-12-04T10:15:00","guid":{"rendered":"https:\/\/www.n2growth.com\/?post_type=interviews&#038;p=142385"},"modified":"2026-07-15T13:23:18","modified_gmt":"2026-07-15T17:23:18","slug":"agcos-ivory-harris-on-the-path-to-chro","status":"publish","type":"interviews","link":"https:\/\/www.n2growth.com\/pt\/interviews\/agcos-ivory-harris-on-the-path-to-chro\/","title":{"rendered":"Ivory Harris, da AGCO, a caminho de se tornar Diretora de Recursos Humanos."},"content":{"rendered":"<section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><img decoding=\"async\" class=\"alignleft wp-image-142384\" src=\"https:\/\/www.n2growth.com\/wp-content\/uploads\/2025\/11\/Ivory-Harris-1-300x278.png\" alt=\"\" width=\"230\" height=\"213\" srcset=\"https:\/\/www.n2growth.com\/wp-content\/uploads\/2025\/11\/Ivory-Harris-1-300x278.png 300w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2025\/11\/Ivory-Harris-1-1024x947.png 1024w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2025\/11\/Ivory-Harris-1-13x12.png 13w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2025\/11\/Ivory-Harris-1-150x139.png 150w, https:\/\/www.n2growth.com\/wp-content\/uploads\/2025\/11\/Ivory-Harris-1.png 1084w\" sizes=\"(max-width: 230px) 100vw, 230px\" \/><\/p>\n<p>\u00c0 medida que as organiza\u00e7\u00f5es elevam os padr\u00f5es para pessoas e desempenho, a responsabilidade do Diretor de Recursos Humanos (CHRO) agora inclui moldar como os l\u00edderes aprendem, decidem e executam. Ivory Harris, Diretora de Recursos Humanos da AGCO, reflete sobre as experi\u00eancias que moldaram sua abordagem, combinando uma mentalidade de lideran\u00e7a servidora com altos padr\u00f5es e uma inclina\u00e7\u00e3o para o progresso. Nesta entrevista, ela oferece orienta\u00e7\u00f5es pr\u00e1ticas para aspirantes a CHROs: amplie sua vis\u00e3o para al\u00e9m das fun\u00e7\u00f5es e geografias, busque exposi\u00e7\u00e3o comercial e priorize a consist\u00eancia em vez da intensidade para sustentar o desempenho. Ela tamb\u00e9m mostra como a autenticidade e a confian\u00e7a reduzem o tempo necess\u00e1rio para gerar impacto.<\/p>\n<p><a href=\"https:\/\/www.linkedin.com\/in\/ivory-harris-b630665\/\">Marfim Harris<\/a> \u00e9 Vice-Presidente S\u00eanior e Diretor de Recursos Humanos da <a href=\"https:\/\/www.agcocorp.com\/us\/en\/home.html\">AGCO<\/a>. A Sra. Harris \u00e9 respons\u00e1vel por liderar o desenvolvimento e a execu\u00e7\u00e3o de estrat\u00e9gias de gest\u00e3o de talentos de alto impacto que geram resultados positivos para os funcion\u00e1rios e stakeholders da AGCO. A Sra. Harris reside em Duluth, Ge\u00f3rgia, EUA.<\/p>\n<\/div><\/div><div class=\"w-separator size_small\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2><span class=\"ez-toc-section\" id=\"Tell_me_about_yourself_What_two_or_three_inflection_points_got_you_to_where_you_are_today_Could_you_highlight_the_stops_along_the_way_and_the_moments_that_shaped_how_you_lead_now\"><\/span>Fale-me sobre voc\u00ea. Quais foram os dois ou tr\u00eas pontos de inflex\u00e3o que o levaram aonde voc\u00ea est\u00e1 hoje? Poderia destacar as etapas ao longo do caminho e os momentos que moldaram a sua lideran\u00e7a atual?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Me considero um l\u00edder servidor. Mas, nascido em Sparta, Illinois, e criado no Texas, tamb\u00e9m sou um lutador nato. Na minha profiss\u00e3o, uso esse DNA para lutar por mudan\u00e7as, promover progresso e gerar impacto.<\/p>\n<p>Um momento decisivo que me marcou foi a compreens\u00e3o que recebi do meu l\u00edder quando cometi um grande erro no trabalho. Recebi um &quot;aviso&quot; para verificar meus dados, mas estava ocupado demais e distra\u00eddo para ouvi-lo. Ent\u00e3o, por obra do destino, o erro se tornou p\u00fablico. Na \u00e9poca, foi um grande problema, uma das maiores mudan\u00e7as na hist\u00f3ria dessa divis\u00e3o da empresa. Pelos meus pr\u00f3prios padr\u00f5es, eu esperava ser demitido. Em vez disso, meu chefe conversou comigo sobre como eu havia cometido o erro, perguntou o que eu havia aprendido com ele e me deu uma chance de me redimir. At\u00e9 ent\u00e3o, eu sempre havia sido visto como um profissional de alto desempenho.<\/p>\n<p>Foi uma mudan\u00e7a de paradigma para mim e transformou meu estilo de lideran\u00e7a. Depois disso, meu chefe passou a me supervisionar mais de perto por um tempo, mas eu tamb\u00e9m me tornei mais atenta aos detalhes e n\u00e3o queria decepcion\u00e1-lo. Ningu\u00e9m era mais focado em qualidade do que eu, e isso permanece comigo at\u00e9 hoje. Estabeleci um padr\u00e3o elevado, equilibrado com humanidade e gentileza. As pessoas respondem melhor quando sentem confian\u00e7a, s\u00e3o consideradas capazes e respons\u00e1veis, perdoadas quando cometem erros e apoiadas em seu crescimento. Pouqu\u00edssimas vezes na minha carreira precisei adotar uma postura mais disciplinadora para impulsionar o desempenho.<\/p>\n<p>Um segundo ponto de inflex\u00e3o marcante foi morar em outro pa\u00eds, liderando uma iniciativa de mudan\u00e7a. Durante esse per\u00edodo, provavelmente aprendi mais sobre mim mesma do que contribu\u00ed para essa fun\u00e7\u00e3o. No entanto, tenho certeza de que, sem essa experi\u00eancia, eu n\u00e3o teria a intelig\u00eancia emocional, a confian\u00e7a, a humildade ou a destreza global necess\u00e1rias para desempenhar com sucesso o trabalho que exer\u00e7o hoje. Esse foi um presente de uma das l\u00edderes mais influentes que j\u00e1 tive, e sou grata por sua vis\u00e3o e investimento di\u00e1rio em mim. Isso n\u00e3o apenas fortaleceu minhas habilidades de lideran\u00e7a, mas tamb\u00e9m aprimorou minha compreens\u00e3o e valoriza\u00e7\u00e3o de experi\u00eancias de aprendizado transformadoras e minha capacidade de ser uma conselheira e parceira confi\u00e1vel e emp\u00e1tica em escala global.<\/p>\n<p>Um ponto crucial que gostaria de compartilhar foi o n\u00edvel de prepara\u00e7\u00e3o para o sucesso que o CEO incluiu no meu plano de integra\u00e7\u00e3o durante meu primeiro ano como CHRO na AGCO. Ele n\u00e3o s\u00f3 estava comprometido com as contribui\u00e7\u00f5es que eu traria para a AGCO, como tamb\u00e9m, ao me ver em transi\u00e7\u00e3o da BASF, pediu que eu deixasse meu trabalho da melhor forma poss\u00edvel. Ele me aconselhou que a forma como voc\u00ea termina \u00e9 t\u00e3o importante quanto a forma como voc\u00ea come\u00e7a. Desde essa primeira conversa, eu soube que tinha tomado a decis\u00e3o certa ao escolher a AGCO.<\/p>\n<p>Antes mesmo de eu assumir oficialmente o cargo, ele elaborou proativamente um plano de 100 dias com insights, metas e relacionamentos essenciais para que eu priorizasse. Al\u00e9m disso, organizou um plano de desenvolvimento e implementa\u00e7\u00e3o de um ano para abranger \u00e1reas nas quais eu n\u00e3o tinha experi\u00eancia pr\u00e9via, mas que eram cruciais para minha nova fun\u00e7\u00e3o, identificou projetos nos quais eu poderia trabalhar para ampliar meu conhecimento organizacional e minha rede de contatos, e agendou reuni\u00f5es quinzenais durante os tr\u00eas primeiros meses para manter contato durante minha transi\u00e7\u00e3o, abordar desafios e oferecer conselhos. Quando me deparei com um obst\u00e1culo inevit\u00e1vel e quis &quot;provar meu valor&quot;, ele me orientou a ser vulner\u00e1vel, aconselhando-me que pedir ajuda era um sinal de autoconhecimento, n\u00e3o de fraqueza. Isso foi transformador para mim.<\/p>\n<p>Em retrospectiva, acredito que esse incentivo e prepara\u00e7\u00e3o me deram a confian\u00e7a necess\u00e1ria para me adaptar rapidamente, criar conex\u00f5es profundas e liderar com ousadia em um novo ambiente. Tamb\u00e9m me tornaram mais confiante, resiliente e preparada para enfrentar obst\u00e1culos. E me deram a coragem de ser uma aprendiz no cargo mais importante da minha carreira. A principal li\u00e7\u00e3o que tirei disso foi o poder de um come\u00e7o extraordin\u00e1rio e o efeito multiplicador que isso pode ter quando aplicado em larga escala. Quero que essa experi\u00eancia seja a norma na AGCO.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"What_experiences_professional_or_personal_even_those_that_seem_unrelated_like_participating_in_a_high_school_or_college_sports_team_have_been_surprisingly_helpful_in_your_role_or_shaped_your_vision_of_leadership_and_how_do_you_apply_those_lessons\"><\/span>Que experi\u00eancias, profissionais ou pessoais (mesmo aquelas que parecem n\u00e3o ter rela\u00e7\u00e3o, como participar de uma equipe esportiva no ensino m\u00e9dio ou na faculdade), foram surpreendentemente \u00fateis em sua fun\u00e7\u00e3o ou moldaram sua vis\u00e3o de lideran\u00e7a, e como voc\u00ea aplica esses ensinamentos?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Quando eu era mais jovem, crescendo no Texas, estava cercada por uma grande fam\u00edlia de trabalhadores dedicados. Meu av\u00f4 era agricultor, minha av\u00f3 educadora, e minha m\u00e3e e tias eram especialistas em medicina ou empreendedorismo. Al\u00e9m da minha fam\u00edlia, tive contato com o trabalho de figuras hist\u00f3ricas importantes da regi\u00e3o, como Barbara Jordan. Desse rico legado, aprendi o valor e o poder da perseveran\u00e7a, da busca por espa\u00e7o, do rigor intelectual e do servi\u00e7o ao pr\u00f3ximo.<\/p>\n<p>Minha trajet\u00f3ria profissional reflete uma convic\u00e7\u00e3o alicer\u00e7ada na humildade, na evolu\u00e7\u00e3o da minha identidade e na disposi\u00e7\u00e3o para abra\u00e7ar novas experi\u00eancias. A converg\u00eancia da minha cria\u00e7\u00e3o moldou meu prop\u00f3sito claro: criar ambientes onde as pessoas possam aproveitar suas perspectivas e percep\u00e7\u00f5es \u00fanicas. Onde elas n\u00e3o s\u00f3 possam contribuir, mas tamb\u00e9m se sintam valorizadas, alcancem seus objetivos pessoais e inspirem outras pessoas a fazerem o mesmo. Onde elas possam sentir a empolga\u00e7\u00e3o de serem aprendizes ao longo da vida, a motiva\u00e7\u00e3o e o crescimento que adv\u00eam da busca constante por resultados, e a resili\u00eancia para descansar, recome\u00e7ar, recarregar as energias e voltar ainda mais fortes.<\/p>\n<p>Sinto-me energizado pelo senso compartilhado de prop\u00f3sito e realiza\u00e7\u00e3o que surge do trabalho em conjunto por algo maior, como alimentar o mundo. Quem n\u00e3o gostaria de fazer parte desta equipe ou ter esta empresa como parceira?<\/p>\n<h2><span class=\"ez-toc-section\" id=\"If_you_were_advising_early-_or_mid-career_leaders_who_want_to_become_CHROs_what_experiences_would_you_seek_out_again_Would_you_stay_in_HR_or_rotate_cross-functionally_and_why\"><\/span>Se voc\u00ea fosse aconselhar l\u00edderes em in\u00edcio ou meio de carreira que desejam se tornar CHROs, que experi\u00eancias voc\u00ea buscaria novamente? Voc\u00ea permaneceria na \u00e1rea de RH ou faria um rod\u00edzio entre diferentes fun\u00e7\u00f5es, e por qu\u00ea?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Tive o privil\u00e9gio de me desenvolver em empresas onde experi\u00eancias diversas me permitiram vivenciar quase todas as \u00e1reas do neg\u00f3cio, trabalhar em diferentes regi\u00f5es geogr\u00e1ficas e liderar e aprender sobre todas as \u00e1reas funcionais de RH. \u00c9 dif\u00edcil quantificar o impacto que isso teve na minha capacidade de me sentir bem informada sobre uma ampla gama de t\u00f3picos e, mais importante, de me conectar com quase todos e me sentir segura nessas conex\u00f5es. Se eu pudesse reescrever minha hist\u00f3ria, incluiria um per\u00edodo de rota\u00e7\u00e3o que n\u00e3o apenas apoiasse o neg\u00f3cio, mas o liderasse, proporcionando experi\u00eancia comercial direta. Acredito que isso n\u00e3o s\u00f3 a tornar\u00e1 uma CHRO ainda mais forte, como tamb\u00e9m poder\u00e1 torn\u00e1-la mais competitiva para se tornar CEO.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Whether_promoted_internally_or_hired_from_outside_what_distinct_strengths_does_each_path_bring_to_the_CHRO_role_For_an_external_arrival_what_helps_shorten_time_to_impact\"><\/span>Seja por meio de promo\u00e7\u00e3o interna ou contrata\u00e7\u00e3o externa, quais s\u00e3o os pontos fortes espec\u00edficos que cada trajet\u00f3ria traz para o cargo de CHRO? Para um profissional contratado externamente, o que ajuda a reduzir o tempo necess\u00e1rio para gerar impacto?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>A promo\u00e7\u00e3o interna pode proporcionar r\u00e1pida aceita\u00e7\u00e3o, adapta\u00e7\u00e3o\/agilidade cultural, conhecimento\/sabedoria organizacional e apoio da rede de contatos, todos fatores essenciais para a jornada de um Diretor de Recursos Humanos (CHRO) a curto e longo prazo.<\/p>\n<p>A promo\u00e7\u00e3o externa pode proporcionar a objetividade necess\u00e1ria, o questionamento do status quo, as melhores pr\u00e1ticas de outros setores, a agilidade para mudan\u00e7as e as perspectivas renovadas que, por vezes, faltam em um sucessor interno. Ser\u00e1 fundamental conquistar seguidores, estabelecer rapidamente conex\u00f5es com as principais partes interessadas (ou seja, a equipe de lideran\u00e7a s\u00eanior, o conselho de administra\u00e7\u00e3o e os agentes de mudan\u00e7a em toda a organiza\u00e7\u00e3o) e cultivar\/estabilizar esses relacionamentos, atuando como um consultor confi\u00e1vel em assuntos\/estrat\u00e9gias de neg\u00f3cios e de pessoas, equilibrando transpar\u00eancia com discri\u00e7\u00e3o e entregando resultados. Os contratados externos devem se adaptar rapidamente e construir confian\u00e7a. \u00c9 a\u00ed que a autenticidade se torna crucial: as pessoas se conectam com l\u00edderes que s\u00e3o genu\u00ednos, que ouvem e que se apresentam com coragem e humildade.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"<p>Uma conversa com Ivory Harris, Vice-Presidente S\u00eanior e Diretora de Recursos Humanos da AGCO.<\/p>","protected":false},"author":1,"featured_media":142384,"template":"","interview-categories":[11364],"class_list":["post-142385","interviews","type-interviews","status-publish","has-post-thumbnail","hentry","interview-categories-people-and-culture"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>AGCO\u2019s Ivory Harris on the path to CHRO<\/title>\n<meta name=\"description\" content=\"In this interview, Ivory Harris, CHRO of AGCO, reflects on the pivotal moments, leadership mindset, and cross-functional experiences that shaped her path to the CHRO role.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.n2growth.com\/pt\/interviews\/agcos-ivory-harris-on-the-path-to-chro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AGCO\u2019s Ivory Harris on the path to CHRO\" \/>\n<meta property=\"og:description\" content=\"In this interview, Ivory Harris, CHRO of AGCO, reflects on the pivotal moments, leadership mindset, and cross-functional experiences that shaped her path to the CHRO role.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.n2growth.com\/pt\/interviews\/agcos-ivory-harris-on-the-path-to-chro\/\" \/>\n<meta property=\"og:site_name\" content=\"N2Growth\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/n2growth\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T17:23:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.n2growth.com\/wp-content\/uploads\/2025\/11\/Ivory-Harris-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1084\" \/>\n\t<meta property=\"og:image:height\" content=\"1003\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@n2growth\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ivory Harris, da AGCO, a caminho de se tornar Diretora de Recursos Humanos.","description":"Nesta entrevista, Ivory Harris, Diretora de Recursos Humanos da AGCO, reflete sobre os momentos cruciais, a mentalidade de lideran\u00e7a e as experi\u00eancias multifuncionais que moldaram sua trajet\u00f3ria at\u00e9 o cargo de Diretora de Recursos Humanos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.n2growth.com\/pt\/interviews\/agcos-ivory-harris-on-the-path-to-chro\/","og_locale":"pt_BR","og_type":"article","og_title":"AGCO\u2019s Ivory Harris on the path to CHRO","og_description":"In this interview, Ivory Harris, CHRO of AGCO, reflects on the pivotal moments, leadership mindset, and cross-functional experiences that shaped her path to the CHRO role.","og_url":"https:\/\/www.n2growth.com\/pt\/interviews\/agcos-ivory-harris-on-the-path-to-chro\/","og_site_name":"N2Growth","article_publisher":"https:\/\/www.facebook.com\/n2growth","article_modified_time":"2026-07-15T17:23:18+00:00","og_image":[{"width":1084,"height":1003,"url":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2025\/11\/Ivory-Harris-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@n2growth","twitter_misc":{"Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.n2growth.com\/interviews\/agcos-ivory-harris-on-the-path-to-chro\/","url":"https:\/\/www.n2growth.com\/interviews\/agcos-ivory-harris-on-the-path-to-chro\/","name":"Ivory Harris, da AGCO, a caminho de se tornar Diretora de Recursos Humanos.","isPartOf":{"@id":"https:\/\/www.n2growth.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.n2growth.com\/interviews\/agcos-ivory-harris-on-the-path-to-chro\/#primaryimage"},"image":{"@id":"https:\/\/www.n2growth.com\/interviews\/agcos-ivory-harris-on-the-path-to-chro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2025\/11\/Ivory-Harris-1.png","datePublished":"2025-12-04T10:15:00+00:00","dateModified":"2026-07-15T17:23:18+00:00","description":"Nesta entrevista, Ivory Harris, Diretora de Recursos Humanos da AGCO, reflete sobre os momentos cruciais, a mentalidade de lideran\u00e7a e as experi\u00eancias multifuncionais que moldaram sua trajet\u00f3ria at\u00e9 o cargo de Diretora de Recursos Humanos.","breadcrumb":{"@id":"https:\/\/www.n2growth.com\/interviews\/agcos-ivory-harris-on-the-path-to-chro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.n2growth.com\/interviews\/agcos-ivory-harris-on-the-path-to-chro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.n2growth.com\/interviews\/agcos-ivory-harris-on-the-path-to-chro\/#primaryimage","url":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2025\/11\/Ivory-Harris-1.png","contentUrl":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2025\/11\/Ivory-Harris-1.png","width":1084,"height":1003},{"@type":"BreadcrumbList","@id":"https:\/\/www.n2growth.com\/interviews\/agcos-ivory-harris-on-the-path-to-chro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.n2growth.com\/"},{"@type":"ListItem","position":2,"name":"AGCO\u2019s Ivory Harris on the path to CHRO"}]},{"@type":"WebSite","@id":"https:\/\/www.n2growth.com\/#website","url":"https:\/\/www.n2growth.com\/","name":"N2Growth","description":"N\u00f3s encontramos e desenvolvemos os melhores l\u00edderes do mundo&#039;","publisher":{"@id":"https:\/\/www.n2growth.com\/#organization"},"alternateName":"N2 Growth","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.n2growth.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.n2growth.com\/#organization","name":"N2Growth","alternateName":"N2 Growth","url":"https:\/\/www.n2growth.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.n2growth.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2019\/05\/N2Growth-Logo-Dark.png","contentUrl":"https:\/\/www.n2growth.com\/wp-content\/uploads\/2019\/05\/N2Growth-Logo-Dark.png","width":500,"height":142,"caption":"N2Growth"},"image":{"@id":"https:\/\/www.n2growth.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/n2growth","https:\/\/x.com\/n2growth","https:\/\/www.instagram.com\/n2growth","https:\/\/www.linkedin.com\/company\/n2growth","https:\/\/www.pinterest.com\/gon2growth\/","https:\/\/www.youtube.com\/c\/n2growth-"],"description":"Empresa global de recrutamento executivo, coaching executivo e consultoria de lideran\u00e7a","email":"press@n2growth.com","telephone":"+18009444662","legalName":"N2Growth Inc.","foundingDate":"2006-05-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}}]}},"_links":{"self":[{"href":"https:\/\/www.n2growth.com\/pt\/wp-json\/wp\/v2\/interviews\/142385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.n2growth.com\/pt\/wp-json\/wp\/v2\/interviews"}],"about":[{"href":"https:\/\/www.n2growth.com\/pt\/wp-json\/wp\/v2\/types\/interviews"}],"author":[{"embeddable":true,"href":"https:\/\/www.n2growth.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.n2growth.com\/pt\/wp-json\/wp\/v2\/media\/142384"}],"wp:attachment":[{"href":"https:\/\/www.n2growth.com\/pt\/wp-json\/wp\/v2\/media?parent=142385"}],"wp:term":[{"taxonomy":"interview-categories","embeddable":true,"href":"https:\/\/www.n2growth.com\/pt\/wp-json\/wp\/v2\/interview-categories?post=142385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}